{"id":973,"date":"2024-02-25T15:53:13","date_gmt":"2024-02-25T15:53:13","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/25\/apos-fracasso-de-vendas-nike-vai-demitir-1-600-funcionarios-para-reduzir-custos\/"},"modified":"2024-02-25T16:21:51","modified_gmt":"2024-02-25T16:21:51","slug":"apos-fracasso-de-vendas-nike-vai-demitir-1-600-funcionarios-para-reduzir-custos","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/25\/apos-fracasso-de-vendas-nike-vai-demitir-1-600-funcionarios-para-reduzir-custos\/","title":{"rendered":"Ap\u00f3s fracasso de vendas, Nike vai demitir 1.600 funcion\u00e1rios para reduzir custos"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: Reprodu\u00e7\u00e3o\/\u201dT\u00eanis de satan\u00e1s\u201d customizados da Nike que cont\u00eam uma gota de sangue humano real nas solas lan\u00e7ado pela MSCHF em colabora\u00e7\u00e3o com o rapper Lil Nas X.<\/p>\n<p>A Nike, uma das principais empresas de vestu\u00e1rio esportivo, revelou em um comunicado na quinta-feira, 15, que pretende demitir aproximadamente 2% de sua for\u00e7a de trabalho, totalizando mais de 1600 colaboradores.<\/p>\n<p>A decis\u00e3o visa reduzir custos diante de proje\u00e7\u00f5es de vendas menos favor\u00e1veis. Em dezembro, a empresa anunciou sua inten\u00e7\u00e3o de economizar US$ 2 bilh\u00f5es nos pr\u00f3ximos tr\u00eas anos, atrav\u00e9s da otimiza\u00e7\u00e3o da for\u00e7a de trabalho e simplifica\u00e7\u00e3o da linha de produtos.<\/p>\n<p>Em declara\u00e7\u00e3o oficial, a Nike afirmou: \u201cAs medidas que estamos adotando nos posicionam para ajustar nosso tamanho organizacional e buscar as maiores oportunidades de crescimento.\u201d<\/p>\n<p>Ap\u00f3s o an\u00fancio, as a\u00e7\u00f5es da Nike registraram uma leve queda de 0,26% no mercado de Nova York, por volta das 7h40 no hor\u00e1rio de Bras\u00edlia.<\/p>\n<p>Os cortes de empregos ocorrer\u00e3o em duas fases, de acordo com um memorando interno da Nike, obtido pela Bloomberg News. A primeira fase est\u00e1 programada para iniciar nesta sexta-feira, 16, e se estender\u00e1 at\u00e9 a pr\u00f3xima semana, enquanto a segunda fase ser\u00e1 conclu\u00edda at\u00e9 o final do quarto trimestre fiscal da empresa.<\/p>\n<p>O an\u00fancio ocorre em um contexto de preocupa\u00e7\u00e3o crescente com o varejo nos Estados Unidos, ap\u00f3s dados indicarem uma queda nas vendas em janeiro, em compara\u00e7\u00e3o com os resultados impulsionados pelo per\u00edodo festivo de dezembro.<\/p>\n<p>Com informa\u00e7\u00f5es da Exame.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/apos-fracasso-de-vendas-nike-vai-demitir-1-600-funcionarios-para-reduzir-custos\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reprodu\u00e7\u00e3o\/\u201dT\u00eanis de satan\u00e1s\u201d customizados da Nike que cont\u00eam uma gota de sangue humano real nas solas lan\u00e7ado pela MSCHF em colabora\u00e7\u00e3o com o rapper Lil Nas X. A Nike, uma das principais empresas de vestu\u00e1rio esportivo, revelou em um comunicado na quinta-feira, 15, que pretende demitir aproximadamente 2% de sua for\u00e7a de trabalho, totalizando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7,1620,1538,1618,864,861,18,459,113,1619],"class_list":["post-973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-apos","tag-custos","tag-demitir","tag-fracasso","tag-funcionarios","tag-nike","tag-para","tag-reduzir","tag-vai","tag-vendas"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=973"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/973\/revisions"}],"predecessor-version":[{"id":975,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/973\/revisions\/975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/974"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}