{"id":92,"date":"2024-02-01T17:38:41","date_gmt":"2024-02-01T17:38:41","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/01\/capital-brasileira-tem-aumento-assustador-de-9205-nos-casos-de-dengue-e-30-mortes\/"},"modified":"2024-02-01T17:42:03","modified_gmt":"2024-02-01T17:42:03","slug":"capital-brasileira-tem-aumento-assustador-de-9205-nos-casos-de-dengue-e-30-mortes","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/01\/capital-brasileira-tem-aumento-assustador-de-9205-nos-casos-de-dengue-e-30-mortes\/","title":{"rendered":"Capital brasileira tem aumento assustador de 920,5% nos casos de dengue e 30 mortes"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>O Distrito Federal enfrenta um alarmante aumento de 920,5% nos casos prov\u00e1veis de dengue. At\u00e9 27 de janeiro deste ano, foram registrados 29.492 diagn\u00f3sticos prov\u00e1veis da doen\u00e7a entre os residentes do DF, em compara\u00e7\u00e3o com os 2.890 casos no mesmo per\u00edodo de 2023, conforme aponta o \u00faltimo boletim epidemiol\u00f3gico da Secretaria de Sa\u00fade.<\/p>\n<p>A situa\u00e7\u00e3o atingiu um ponto cr\u00edtico, levando o governo a declarar estado de emerg\u00eancia devido \u00e0 explos\u00e3o de casos de dengue. A capital federal destaca-se como a unidade da Federa\u00e7\u00e3o com o cen\u00e1rio mais preocupante do pa\u00eds, especialmente quando os n\u00fameros s\u00e3o avaliados em rela\u00e7\u00e3o \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>O boletim revela que a faixa et\u00e1ria entre 20 e 29 anos \u00e9 a mais afetada proporcionalmente, com uma incid\u00eancia de 1.092,2 casos por 100 mil habitantes.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0s fatalidades, foram confirmadas seis mortes pela doen\u00e7a, enquanto outras 24 est\u00e3o sendo investigadas. At\u00e9 29 de janeiro, foram registrados \u00f3bitos de cinco homens e uma mulher. As v\u00edtimas incluem uma crian\u00e7a com idade divulgada entre 5 e 9 anos, dois jovens entre 20 e 39 anos, uma pessoa entre 40 e 49 anos, e dois idosos entre 70 e 79 anos. As \u00e1reas mais afetadas foram Ceil\u00e2ndia (2), Guar\u00e1 (2), Estrutural (1) e Lago Sul (1).<\/p>\n<p><strong>Com informa\u00e7\u00f5es Metr\u00f3poles<\/strong><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/capital-brasileira-tem-aumento-assustador-de-9205-nos-casos-de-dengue-e-30-mortes\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Distrito Federal enfrenta um alarmante aumento de 920,5% nos casos prov\u00e1veis de dengue. At\u00e9 27 de janeiro deste ano, foram registrados 29.492 diagn\u00f3sticos prov\u00e1veis da doen\u00e7a entre os residentes do DF, em compara\u00e7\u00e3o com os 2.890 casos no mesmo per\u00edodo de 2023, conforme aponta o \u00faltimo boletim epidemiol\u00f3gico da Secretaria de Sa\u00fade. A situa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":93,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[98,97,96,95,100,101,102,99,59],"class_list":["post-92","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-assustador","tag-aumento","tag-brasileira","tag-capital","tag-casos","tag-dengue","tag-mortes","tag-nos","tag-tem"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/92\/revisions"}],"predecessor-version":[{"id":94,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/92\/revisions\/94"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/93"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=92"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=92"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}