{"id":915,"date":"2024-02-23T22:37:20","date_gmt":"2024-02-23T22:37:20","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/23\/globo-da-ultimato-e-impoe-condicao-para-nao-demitir-fatima-bernardes\/"},"modified":"2024-02-24T08:49:57","modified_gmt":"2024-02-24T08:49:57","slug":"globo-da-ultimato-e-impoe-condicao-para-nao-demitir-fatima-bernardes","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/23\/globo-da-ultimato-e-impoe-condicao-para-nao-demitir-fatima-bernardes\/","title":{"rendered":"Globo d\u00e1 ultimato e imp\u00f5e condi\u00e7\u00e3o para n\u00e3o demitir F\u00e1tima Bernardes\u00a0"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Reprodu\u00e7\u00e3o\/Rede Globo<\/p>\n<h2 class=\"wp-block-heading\">Caso o contrato com a emissora seja encerrado, esta ser\u00e1 a primeira vez desde 1989 que a jornalista n\u00e3o comandar\u00e1 uma atra\u00e7\u00e3o no canal<\/h2>\n<p>Na tarde desta sexta-feira (23), o jornalista Alessandro Lo-Bianco divulgou com exclusividade, durante o programa \u201cA Tarde \u00c9 Sua\u201d, da RedeTV!, que a apresentadora F\u00e1tima Bernardes recebeu um aviso da Rede Globo. De acordo com o comunicador, a jornalista tem pouco um pouco mais de trinta dias para apresentar um novo projeto \u00e0 emissora dos Marinho, caso o contr\u00e1rio, ela ser\u00e1 demitida. Esta n\u00e3o \u00e9 a primeira vez que ele aponta que\u00a0<strong>o emprego da ex-mulher de William Bonner est\u00e1 em risco.<\/strong><\/p>\n<p>De acordo com uma das fontes de Lo-Bianco, a Rede Globo deu um prazo para que F\u00e1tima Bernardes sugerisse um novo programa ao canal.\u00a0<em>\u201cAt\u00e9 31 de mar\u00e7o para que a F\u00e1tima apresente um projeto\u201d<\/em>, revelou. Conforme o que foi divulgado pelo jornalista, a ex-apresentadora do \u201cThe Voice Brasil\u201d n\u00e3o teria o interesse de apresentar nada. Desta forma, caso nada chegue \u00e0 mesa dos chef\u00f5es da Globo, a ex-\u00e2ncora do Jornal Nacional n\u00e3o continuar\u00e1 na emissora at\u00e9 o final deste ano.<\/p>\n<p><em>\u201cEm abril, a Globo em conjunto com a F\u00e1tima divulgaria um comunicado falando do t\u00e9rmino da rela\u00e7\u00e3o contratual dela\u201d<\/em>, Lo-Bianco contou os pr\u00f3ximos passos da emissora e de sua at\u00e9 ent\u00e3o contratada caso as coisas n\u00e3o avancem. O jornalista tamb\u00e9m lembrou da not\u00edcia divulgada ontem (22), pelo colunista Gabriel Vaquer, do portal F5, da Folha de S\u00e3o Paulo. De acordo com o comunicador, al\u00e9m da emissora do Plim-Plim\u00a0<strong>n\u00e3o possui planos<\/strong> de produzir uma segunda temporada do \u201cAssim Como A Gente\u201d, que era apresentado por F\u00e1tima Bernardes e transmitido pela GNT, tamb\u00e9m n\u00e3o existe nenhuma estrat\u00e9gia a curto prazo para encaix\u00e1-la em um outro programa.<\/p>\n<p>A informa\u00e7\u00e3o de Vaquer foi confirmada pela pr\u00f3pria emissora da TV fechada.\u00a0<em>\u201cN\u00e3o temos a confirma\u00e7\u00e3o de uma nova temporada no momento, pois a programa\u00e7\u00e3o de 2024 ainda est\u00e1 em constru\u00e7\u00e3o com algumas atra\u00e7\u00f5es j\u00e1 confirmadas e outras sendo adiantadas. \u00c9 algo comum no GNT, que tem um planejamento din\u00e2mico\u201d<\/em>, a GNT disse em nota. Caso o contrato de F\u00e1tima Bernardes com a Globo seja encerrado ap\u00f3s o prazo estipulado pela emissora, esta ser\u00e1 a primeira vez desde 1989 que a jornalista n\u00e3o estar\u00e1 a frente de uma atra\u00e7\u00e3o do canal.<\/p>\n<p>Em Off<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/globo-da-ultimato-e-impoe-condicao-para-nao-demitir-fatima-bernardes\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reprodu\u00e7\u00e3o\/Rede Globo Caso o contrato com a emissora seja encerrado, esta ser\u00e1 a primeira vez desde 1989 que a jornalista n\u00e3o comandar\u00e1 uma atra\u00e7\u00e3o no canal Na tarde desta sexta-feira (23), o jornalista Alessandro Lo-Bianco divulgou com exclusividade, durante o programa \u201cA Tarde \u00c9 Sua\u201d, da RedeTV!, que a apresentadora F\u00e1tima Bernardes recebeu um aviso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1539,1537,470,1538,740,108,1536,165,18,1535],"class_list":["post-915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-bernardes","tag-condicao","tag-da","tag-demitir","tag-fatima","tag-globo","tag-impoe","tag-nao","tag-para","tag-ultimato"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=915"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/915\/revisions"}],"predecessor-version":[{"id":917,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/915\/revisions\/917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/916"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}