{"id":84,"date":"2024-02-01T16:30:43","date_gmt":"2024-02-01T16:30:43","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/01\/medicamentos-devem-ficar-mais-caros-apos-novo-reajuste-no-brasil-veja\/"},"modified":"2024-02-01T16:35:24","modified_gmt":"2024-02-01T16:35:24","slug":"medicamentos-devem-ficar-mais-caros-apos-novo-reajuste-no-brasil-veja","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/01\/medicamentos-devem-ficar-mais-caros-apos-novo-reajuste-no-brasil-veja\/","title":{"rendered":"Medicamentos devem ficar mais caros ap\u00f3s novo reajuste no Brasil; VEJA"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>O aumento do ICMS em 10 estados e no Distrito Federal est\u00e1 previsto para resultar em um aumento nos custos dos medicamentos no Brasil, de acordo com a Associa\u00e7\u00e3o Brasileira de Redes de Farm\u00e1cias e Drogarias (Abrafarma).<\/p>\n<p>A Abrafarma afirma que as varia\u00e7\u00f5es de 1% a 2% no imposto certamente ser\u00e3o repassadas aos consumidores por meio do aumento nos pre\u00e7os dos medicamentos.<\/p>\n<p>Embora as Unidades da Federa\u00e7\u00e3o que est\u00e3o implementando o reajuste argumentem que a medida \u00e9 necess\u00e1ria para compensar as perdas de arrecada\u00e7\u00e3o, a Abrafarma considera esse argumento superficial, pois n\u00e3o leva em considera\u00e7\u00e3o o impacto direto sobre os consumidores.<\/p>\n<p>\u201cEnquanto o Brasil experimenta um vi\u00e9s de redu\u00e7\u00e3o da infla\u00e7\u00e3o e dos juros, aliado \u00e0 aprova\u00e7\u00e3o da reforma tribut\u00e1ria, esses governos caminham na contram\u00e3o e demonstram insensibilidade com a popula\u00e7\u00e3o mais pobre\u201d, critica Sergio Mena Barreto, CEO da Abrafarma.<\/p>\n<p>De acordo com a associa\u00e7\u00e3o, a carga tribut\u00e1ria sobre medicamentos no pa\u00eds j\u00e1 \u00e9 seis vezes mais alta que no restante do mundo.<\/p>\n<h2 class=\"wp-block-heading\">Confira os estados com eleva\u00e7\u00e3o de ICMS<\/h2>\n<ul>\n<li>Bahia: 19% para 20,5% \u2013 em Fev\/24<\/li>\n<li>Cear\u00e1: 18% para 20% \u2013 em Jan\/24<\/li>\n<li>Distrito Federal: 18% para 20% \u2013 em Jan\/24<\/li>\n<li>Goi\u00e1s: 17% para 19% \u2013 em Abr\/24<\/li>\n<li>Maranh\u00e3o: 20% para 22% \u2013 em Fev\/24<\/li>\n<li>Para\u00edba: 18% para 20% \u2013 em Jan\/24<\/li>\n<li>Paran\u00e1: 19% para 19,5% \u2013 em Mar\/24<\/li>\n<li>Pernambuco: 18% para 20,5% \u2013 em Jan\/24<\/li>\n<li>Rio de Janeiro: 20% para 22% \u2013 em Mar\/24<\/li>\n<li>Rond\u00f4nia: 17,5% para 19,5% \u2013 em Jan\/24<\/li>\n<li>Tocantins: 18% para 20% \u2013 em Jan\/24<\/li>\n<\/ul>\n<p>S\u00e3o Paulo e Rio Grande do Sul chegaram a sinalizar aumentar o ICMS para 2024, mas recuaram da decis\u00e3o.<\/p>\n<p>Com informa\u00e7\u00f5es da <strong>CNN Brasil<\/strong><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/medicamentos-devem-ficar-mais-caros-apos-novo-reajuste-no-brasil-veja\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O aumento do ICMS em 10 estados e no Distrito Federal est\u00e1 previsto para resultar em um aumento nos custos dos medicamentos no Brasil, de acordo com a Associa\u00e7\u00e3o Brasileira de Redes de Farm\u00e1cias e Drogarias (Abrafarma). A Abrafarma afirma que as varia\u00e7\u00f5es de 1% a 2% no imposto certamente ser\u00e3o repassadas aos consumidores por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":85,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7,94,92,89,90,91,88,79,93,11],"class_list":["post-84","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-apos","tag-brasil","tag-caros","tag-devem","tag-ficar","tag-mais","tag-medicamentos","tag-novo","tag-reajuste","tag-veja"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/84\/revisions"}],"predecessor-version":[{"id":86,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/84\/revisions\/86"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/85"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=84"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=84"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}