{"id":802,"date":"2024-02-21T22:34:21","date_gmt":"2024-02-21T22:34:21","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/21\/mc-gui-emagrece-17-kg-e-assusta-seguidores-com-antes-e-depois-veja-as-fotos\/"},"modified":"2024-02-22T07:52:09","modified_gmt":"2024-02-22T07:52:09","slug":"mc-gui-emagrece-17-kg-e-assusta-seguidores-com-antes-e-depois-veja-as-fotos","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/21\/mc-gui-emagrece-17-kg-e-assusta-seguidores-com-antes-e-depois-veja-as-fotos\/","title":{"rendered":"MC Gui emagrece 17 kg e assusta seguidores com antes e depois; veja as fotos"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>REPRODU\u00c7\u00c3O\/INSTAGRAM<\/p>\n<p>MC Gui\u00a0emagreceu 17 kg desde que come\u00e7ou a treinar para competir em lutas h\u00e1 seis meses. O cantor revelou que conseguiu perder peso apenas com reeduca\u00e7\u00e3o alimentar e exerc\u00edcios f\u00edsicos. Internautas lotaram caixas de perguntas no\u00a0Instagram\u00a0do artista e o questionaram se ele estava usando drogas. A diferen\u00e7a \u00e9 percept\u00edvel no rosto do funkeiro.<\/p>\n<p>Nesta quarta (21), Gui que acredita j\u00e1 ter emagrecido bem mais do que j\u00e1 contabilizou. \u201cAt\u00e9 agora foram 17 kg perdidos de balan\u00e7a, fora o que a gente trocou de massa ruim por massa boa. Acredito que beirou perto dos 20 kg. Na verdade, nem eu acredito\u201d, brincou.<\/p>\n<p>O ex-participante de\u00a0A Fazenda\u00a0reagiu a coment\u00e1rios feitos em uma publica\u00e7\u00e3o do jornalista Luiz Bacci. Internautas sugeriram que ele estaria fumando crack e que, por isso, teria emagrecido quase 20 kg.<\/p>\n<p>\u201cSobre esses coment\u00e1rios: est\u00e1 tudo bem, porque eu sou um cara que fa\u00e7o as coisas atrav\u00e9s do que eu quero, dos meus sentimentos. Eu jamais vou querer emagrecer porque o povo est\u00e1 falando que eu estou gordo. Jamais vou engordar porque est\u00e3o falando que eu estou muito magro. Geralmente dou muita risada com os haters\u201d, disparou.<\/p>\n<p>\u201cEstou comendo bem, treinando bem e me cuidando. Coisa que muita gente n\u00e3o consegue fazer. \u00c0s vezes, \u00e9 mais f\u00e1cil falar que a gente est\u00e1 fumando pedra? \u00c9. Mas me sinto bem, hein? Se isso aqui \u00e9 ser um cracudo, o pai \u00e9 um cracudo com estilo\u201d, debochou MC Gui.<\/p>\n<p>A voz de O Bonde Passou ir\u00e1 enfrentar\u00a0Nego do Borel\u00a0em uma luta neste s\u00e1bado (24). Em entrevista ao Portal Leo Dias, ele revelou que parou de ingerir bebidas alco\u00f3licas e passou a seguir a risca uma tabela de suplementos indicados por um nutricionista.<\/p>\n<p>\u201cEu gosto de beber, mas nesse momento estou focado na dieta e nem na dose de \u00e1gua posso passar. \u00c9 uma dieta super restrita. O mais importante foi o acompanhamento com os rem\u00e9dios manipulados. Tem muita gente que usa testosterona, j\u00e1 usei, n\u00e3o julgo, mas n\u00e3o pude desta vez porque tinha de perder o peso e com isso n\u00e3o manteria\u201d, disse.<\/p>\n<p>Confira abaixo o antes e depois de MC Gui:<\/p>\n<p>reprodu\u00e7\u00e3o\/instagram<\/p>\n<\/p>\n<p>MC Gui se prepara para competir nos ringues<\/p>\n<p>reprodu\u00e7\u00e3o\/instagram<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" alt=\"MC Gui\" height=\"394\" src=\"https:\/\/noticiasdatv.uol.com.br\/media\/uploads\/artigos_2023\/mc-gui-antes-depois-foto-instagram.jpg\" width=\"630\"\/><\/p>\n<p>MC Gui em 2022 (\u00e0 esquerda) e hoje (direita)<\/p>\n<p>Not\u00edcias na TV<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/mc-gui-emagrece-17-kg-assusta-seguidores-com-antes-e-depois-veja-as-fotos\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REPRODU\u00c7\u00c3O\/INSTAGRAM MC Gui\u00a0emagreceu 17 kg desde que come\u00e7ou a treinar para competir em lutas h\u00e1 seis meses. O cantor revelou que conseguiu perder peso apenas com reeduca\u00e7\u00e3o alimentar e exerc\u00edcios f\u00edsicos. Internautas lotaram caixas de perguntas no\u00a0Instagram\u00a0do artista e o questionaram se ele estava usando drogas. A diferen\u00e7a \u00e9 percept\u00edvel no rosto do funkeiro. Nesta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[594,1373,183,217,335,1372,852,11],"class_list":["post-802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-antes","tag-assusta","tag-depois","tag-emagrece","tag-fotos","tag-gui","tag-seguidores","tag-veja"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=802"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/802\/revisions"}],"predecessor-version":[{"id":804,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/802\/revisions\/804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/803"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}