{"id":787,"date":"2024-02-21T23:29:14","date_gmt":"2024-02-21T23:29:14","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/21\/grave-brasileira-que-estava-nos-ataques-do-hamas-em-israel-diz-que-nao-volta-para-o-brasil-com-medo-de-perseguicao-a-judeus\/"},"modified":"2024-02-22T01:23:50","modified_gmt":"2024-02-22T01:23:50","slug":"grave-brasileira-que-estava-nos-ataques-do-hamas-em-israel-diz-que-nao-volta-para-o-brasil-com-medo-de-perseguicao-a-judeus","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/21\/grave-brasileira-que-estava-nos-ataques-do-hamas-em-israel-diz-que-nao-volta-para-o-brasil-com-medo-de-perseguicao-a-judeus\/","title":{"rendered":"Grave: brasileira que estava nos ataques do Hamas em Israel diz que n\u00e3o volta para o Brasil com medo de persegui\u00e7\u00e3o a judeus:"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: Divulga\u00e7\u00e3o<\/p>\n<h2 class=\"wp-block-heading\">O v\u00eddeo foi gravado ao lado do chanceler israelense Israel Katz<\/h2>\n<p>A brasileira Rafaela Triestman, 20 anos, sobrevivente do ataque terrorista do Hamas no sul de Israel no dia 7 de outubro de 2023, gravou um v\u00eddeo para mostrar sua indigna\u00e7\u00e3o com a fala do presidente Luiz In\u00e1cio Lula da Silva (PT) que comparou a guerra em Gaza com o Holocausto judeu.<\/p>\n<p>Rafaela \u00e9 neta de judeus poloneses que sobreviveram ao Holocausto e se mudaram para o Brasil buscando um pa\u00eds seguro. Ela mora em Israel h\u00e1 tr\u00eas anos e estava no festival de m\u00fasica que foi atacado pelos terroristas naquela noite.<\/p>\n<p>A jovem namorava o brasileiro Ranani Glazer, de 24 anos, que foi morto pelos soldados do Hamas, e contou com detalhes todo o horror que ela viveu no dia do ataque, incluindo ter que ficar cinco horas debaixo de corpos de jovens que tamb\u00e9m estavam na festa e foram executados com crueldade pelos terroristas.<\/p>\n<p>Sobre Lula, Rafaela diz estar triste com a declara\u00e7\u00e3o, pois Israel oferece muita ajuda para os palestinos e oportunidades para que os \u00e1rabes possam conviver em paz.<\/p>\n<p>\u2013 Me entristece muito saber que o pa\u00eds onde eu nasci, o pa\u00eds que eu chamo de casa est\u00e1 nesta situa\u00e7\u00e3o. Onde o governo compara as atitudes de Israel com o Holocausto \u2013 disse.<\/p>\n<p>No v\u00eddeo, a jovem tamb\u00e9m reclama que o governo brasileiro n\u00e3o deu nenhuma assist\u00eancia para as fam\u00edlias dos cidad\u00e3os brasileiros que foram mortos pelo Hamas, enquanto Israel tem pagado medica\u00e7\u00e3o e tratamento psicol\u00f3gico aos sobreviventes.<\/p>\n<p><strong>Assista:<\/strong><\/p>\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\">\n<div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"pt\" dir=\"ltr\">A brasileira Rafaela Triestman estava no festival de m\u00fasica Nova quando terroristas do Hamas atacaram Israel, em 7 de outubro.<\/p>\n<p>Rafaela sobreviveu, mas seu namorado Ranani Glazer foi brutalmente assassinado por terroristas do Hamas, juntamente com v\u00e1rios dos seus amigos.\u2026 <a href=\"https:\/\/t.co\/pbUIYbO5hk\">pic.twitter.com\/pbUIYbO5hk<\/a><\/p>\n<p>\u2014 \u05d9\u05e9\u05e8\u05d0\u05dc \u05db\u201d\u05e5 Israel Katz (@Israel_katz) <a href=\"https:\/\/twitter.com\/Israel_katz\/status\/1760332592136483172?ref_src=twsrc%5Etfw\">February 21, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/figure>\n<p>Pleno News <\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/grave-brasileira-que-estava-nos-ataques-do-hamas-em-israel-diz-que-nao-volta-para-o-brasil-com-medo-de-perseguicao-a-judeus-eles-queimaram-meus-amigos-vivos-veja-video\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Divulga\u00e7\u00e3o O v\u00eddeo foi gravado ao lado do chanceler israelense Israel Katz A brasileira Rafaela Triestman, 20 anos, sobrevivente do ataque terrorista do Hamas no sul de Israel no dia 7 de outubro de 2023, gravou um v\u00eddeo para mostrar sua indigna\u00e7\u00e3o com a fala do presidente Luiz In\u00e1cio Lula da Silva (PT) que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[21,94,96,243,1351,544,1263,1049,1354,1352,165,99,18,1353,619],"class_list":["post-787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-ataques","tag-brasil","tag-brasileira","tag-diz","tag-estava","tag-grave","tag-hamas","tag-israel","tag-judeus","tag-medo","tag-nao","tag-nos","tag-para","tag-perseguicao","tag-volta"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=787"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/787\/revisions"}],"predecessor-version":[{"id":789,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/787\/revisions\/789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/788"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}