{"id":737,"date":"2024-02-20T23:08:14","date_gmt":"2024-02-20T23:08:14","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/20\/mega-sena-confira-o-resultado-do-sorteio-2690-desta-terca-20-premio-e-de-r-867-milhoes\/"},"modified":"2024-02-21T05:26:49","modified_gmt":"2024-02-21T05:26:49","slug":"mega-sena-confira-o-resultado-do-sorteio-2690-desta-terca-20-premio-e-de-r-867-milhoes","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/20\/mega-sena-confira-o-resultado-do-sorteio-2690-desta-terca-20-premio-e-de-r-867-milhoes\/","title":{"rendered":"Mega-Sena: confira o resultado do sorteio 2690 desta ter\u00e7a (20); pr\u00eamio \u00e9 de R$ 86,7 milh\u00f5es"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Na noite desta ter\u00e7a-feira (20\/2), a Caixa Econ\u00f4mica Federal realizou sorteios de cinco loterias diferentes: Mega-Sena (concurso 2690), Quina (concurso 6370), Lotof\u00e1cil (concurso 3033), Timemania (concurso 2056) e Dia da Sorte (concurso 877). O evento aconteceu no Espa\u00e7o Caixa Loterias, situado no novo Espa\u00e7o da Sorte, localizado na Avenida Paulista, em S\u00e3o Paulo.<\/p>\n<p>Para a Mega-Sena, que oferecia um pr\u00eamio estimado de R$86,7 milh\u00f5es, as dezenas sorteadas foram: <strong>09-28-33-43-45-55<\/strong>. <\/p>\n<p>Informa\u00e7\u00f5es sobre a quantidade de ganhadores e a distribui\u00e7\u00e3o do pr\u00eamio podem ser verificadas na p\u00e1gina oficial da Caixa Econ\u00f4mica Federal.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/mega-sena-confira-o-resultado-do-sorteio-2690-desta-terca-20-premio-e-de-r-867-milhoes\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite desta ter\u00e7a-feira (20\/2), a Caixa Econ\u00f4mica Federal realizou sorteios de cinco loterias diferentes: Mega-Sena (concurso 2690), Quina (concurso 6370), Lotof\u00e1cil (concurso 3033), Timemania (concurso 2056) e Dia da Sorte (concurso 877). O evento aconteceu no Espa\u00e7o Caixa Loterias, situado no novo Espa\u00e7o da Sorte, localizado na Avenida Paulista, em S\u00e3o Paulo. Para a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[322,541,815,365,1284,1182,1282,1283],"class_list":["post-737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-confira","tag-desta","tag-megasena","tag-milhoes","tag-premio","tag-resultado","tag-sorteio","tag-terca"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=737"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/737\/revisions"}],"predecessor-version":[{"id":739,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/737\/revisions\/739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/738"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}