{"id":677,"date":"2024-02-19T22:45:50","date_gmt":"2024-02-19T22:45:50","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/19\/agora-sinal-de-celular-dos-presos-que-fugiram-da-penitenciaria-de-mossoro-foi-detectado-pela-ultima-vez-veja-onde\/"},"modified":"2024-02-20T06:53:03","modified_gmt":"2024-02-20T06:53:03","slug":"agora-sinal-de-celular-dos-presos-que-fugiram-da-penitenciaria-de-mossoro-foi-detectado-pela-ultima-vez-veja-onde","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/19\/agora-sinal-de-celular-dos-presos-que-fugiram-da-penitenciaria-de-mossoro-foi-detectado-pela-ultima-vez-veja-onde\/","title":{"rendered":"AGORA: sinal de celular dos presos que fugiram da penitenci\u00e1ria de Mossor\u00f3\u00a0foi detectado pela \u00faltima vez; veja onde"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: Reprodu\u00e7\u00e3o \/ GloboNews\u00a0<\/p>\n<p>Sinal de celular de fugitivos de penitenci\u00e1ria indica que eles est\u00e3o entre RN e CE\u00a0<\/p>\n<p>As investiga\u00e7\u00f5es sobre a fuga de dois detentos do pres\u00eddio de seguran\u00e7a m\u00e1xima de Mossor\u00f3 (RN) apontam que o\u00a0<strong>\u00faltimo sinal obtido de celular dos fugitivos<\/strong>\u00a0foi no s\u00e1bado (17), em \u00e1rea rural, perto da divisa do rio Grande do Norte com o Cear\u00e1.\u00a0<\/p>\n<p>Desde ent\u00e3o, os\u00a0dois celulares roubados de moradores de uma casa que foi invadida pelos detentos na sexta-feira (16)silenciaram. A suspeita dos investigadores \u00e9 de os aparelhos que tenham ficado sem bateria. Al\u00e9m de roubar os celulares, os fugitivos comeram, pediram para entrar em redes sociais e assistiram a not\u00edcias sobre a fuga. A casa fica a cerca de tr\u00eas quil\u00f4metros da Penitenci\u00e1ria Federal de Mossor\u00f3, na comunidade de Riacho Grande.\u00a0<\/p>\n<p>Os principais envolvidos na for\u00e7a-tarefa de recaptura acreditam que os dois criminosos permanecem na regi\u00e3o e n\u00e3o conseguiram abrir muita dist\u00e2ncia do local do pres\u00eddio.<\/p>\n<p>Nesta segunda (19), os\u00a0policiais intensificam buscas por Rog\u00e9rio Mendon\u00e7a e Deibson Nascimento em cidade na divisa com o Cear\u00e1.\u00a0<\/p>\n<p>Em visita a Mossor\u00f3 neste domingo (18), o ministro da Justi\u00e7a e da Seguran\u00e7a P\u00fablica, Ricardo Lewandowski, alegou que a complexidade do terreno \u00e9 um ponto de dificuldade para os trabalhos.\u00a0Tamb\u00e9m afirmou que n\u00e3o h\u00e1 prazo para a captura dos presos.\u00a0<\/p>\n<p>A opera\u00e7\u00e3o conta com helic\u00f3pteros, drones, c\u00e3es farejadores e outros equipamentos tecnol\u00f3gicos sofisticados, al\u00e9m de mais de 500 homens das for\u00e7as de seguran\u00e7a estaduais e federal.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/agora-sinal-de-celular-dos-presos-que-fugiram-da-penitenciaria-de-mossoro-foi-detectado-pela-ultima-vez-veja-onde\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reprodu\u00e7\u00e3o \/ GloboNews\u00a0 Sinal de celular de fugitivos de penitenci\u00e1ria indica que eles est\u00e3o entre RN e CE\u00a0 As investiga\u00e7\u00f5es sobre a fuga de dois detentos do pres\u00eddio de seguran\u00e7a m\u00e1xima de Mossor\u00f3 (RN) apontam que o\u00a0\u00faltimo sinal obtido de celular dos fugitivos\u00a0foi no s\u00e1bado (17), em \u00e1rea rural, perto da divisa do rio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[43,906,1191,20,674,1190,1193,159,849,6,1189,1192,11,212],"class_list":["post-677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-agora","tag-celular","tag-detectado","tag-dos","tag-fugiram","tag-mossorofoi","tag-onde","tag-pela","tag-penitenciaria","tag-presos","tag-sinal","tag-ultima","tag-veja","tag-vez"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=677"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/677\/revisions"}],"predecessor-version":[{"id":679,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/677\/revisions\/679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/678"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}