{"id":539,"date":"2024-02-17T22:06:47","date_gmt":"2024-02-17T22:06:47","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/17\/tse-analisa-acordo-entre-big-techs-para-combater-fake-news-geradas-por-ia-nas-eleicoes\/"},"modified":"2024-02-18T01:34:13","modified_gmt":"2024-02-18T01:34:13","slug":"tse-analisa-acordo-entre-big-techs-para-combater-fake-news-geradas-por-ia-nas-eleicoes","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/17\/tse-analisa-acordo-entre-big-techs-para-combater-fake-news-geradas-por-ia-nas-eleicoes\/","title":{"rendered":"TSE analisa acordo entre Big Techs para combater Fake News geradas por IA nas elei\u00e7\u00f5es"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: Reprodu\u00e7\u00e3o.<\/p>\n<p>Na Confer\u00eancia de Seguran\u00e7a de Munique, realizada na Alemanha nesta sexta-feira (16), 20 empresas l\u00edderes de tecnologia, incluindo Adobe, Amazon, Google, IBM, Meta, Microsoft, OpenAI, TikTok e X (antigo Twitter), uniram for\u00e7as para enfrentar o desafio das fake news geradas por intelig\u00eancia artificial (IA) durante as elei\u00e7\u00f5es de 2024. O objetivo \u00e9 prevenir a dissemina\u00e7\u00e3o de conte\u00fado enganoso em mais de 40 pa\u00edses onde ocorrer\u00e3o processos eleitorais.<\/p>\n<p>Um comunicado conjunto das empresas destaca que o acordo estabelece \u201ccompromissos para implementar tecnologias que combatam o conte\u00fado prejudicial gerado por IA com o intuito de enganar os eleitores\u201d.<\/p>\n<p>As empresas tamb\u00e9m se comprometeram a \u201ctrabalhar em conjunto no desenvolvimento de ferramentas para detectar e combater a dissemina\u00e7\u00e3o online desse conte\u00fado gerado por IA, promover campanhas educativas e fornecer transpar\u00eancia, entre outras medidas concretas. O acordo inclui uma s\u00e9rie abrangente de princ\u00edpios, como a import\u00e2ncia de rastrear a origem de conte\u00fados fraudulentos relacionados \u00e0s elei\u00e7\u00f5es e a necessidade de conscientizar o p\u00fablico sobre o problema\u201d.<\/p>\n<p>O conte\u00fado digital abordado pelo acordo inclui \u00e1udio, v\u00eddeo e imagens gerados por IA que falsificam ou alteram de maneira enganosa a apar\u00eancia, voz ou a\u00e7\u00f5es de candidatos pol\u00edticos, autoridades eleitorais e outras partes interessadas fundamentais em um processo eleitoral democr\u00e1tico, ou que fornecem informa\u00e7\u00f5es falsas aos eleitores sobre quando, onde e como votar.<\/p>\n<p>\u201cTheo Bertram, vice-presidente de pol\u00edticas p\u00fablicas globais do TikTok, destacou: \u201c\u00c9 crucial que a ind\u00fastria trabalhe em conjunto para proteger as comunidades contra a IA enganosa e fraudulenta neste ano eleitoral crucial\u201d. Ele enfatizou que isso se baseia no cont\u00ednuo investimento em prote\u00e7\u00e3o da integridade eleitoral e no avan\u00e7o de pr\u00e1ticas respons\u00e1veis e transparentes de conte\u00fado gerado por IA, por meio de regras robustas, novas tecnologias e parcerias de educa\u00e7\u00e3o midi\u00e1tica com especialistas\u201d.<\/p>\n<h4 class=\"wp-block-heading\">TSE em an\u00e1lise<\/h4>\n<p> No Brasil, o Tribunal Superior Eleitoral (TSE) est\u00e1 estudando o tema e deve elaborar uma resolu\u00e7\u00e3o sobre o uso da IA nas campanhas eleitorais deste ano. Em janeiro, foi iniciado um ciclo de audi\u00eancias p\u00fablicas para debater sugest\u00f5es aos textos das regras que orientar\u00e3o as elei\u00e7\u00f5es municipais.<\/p>\n<p>A Corte Eleitoral recebeu quase mil propostas de aperfei\u00e7oamento das 10 minutas de resolu\u00e7\u00f5es que tratam do pleito eleitoral deste ano. Os textos s\u00e3o relatados pela vice-presidente do TSE, ministra C\u00e1rmen L\u00facia, que presidir\u00e1 o tribunal durante as elei\u00e7\u00f5es.<\/p>\n<p>Entre as sugest\u00f5es, est\u00e1 a de que o uso da IA na campanha seja explicitamente informado, assim como destaque sobre o conte\u00fado fabricado ou manipulado e a tecnologia utilizada.<\/p>\n<p>O texto pro\u00edbe a utiliza\u00e7\u00e3o de IA para fabricar ou manipular conte\u00fado com \u201cfatos sabidamente inver\u00eddicos ou gravemente descontextualizados com potencial de causar danos ao equil\u00edbrio do pleito ou \u00e0 integridade do processo eleitoral\u201d.<\/p>\n<p>A\u00e7\u00f5es propostas pelas Big Techs As plataformas digitais sugeriram ajustes na minuta de resolu\u00e7\u00e3o sobre propaganda eleitoral da Corte para evitar sua eventual responsabiliza\u00e7\u00e3o por conte\u00fados impulsionados ou postagens com desinforma\u00e7\u00e3o sobre o processo eleitoral. As mudan\u00e7as foram defendidas por representantes do Facebook, Google e YouTube e ainda passar\u00e3o por an\u00e1lise do TSE, assim como as sugest\u00f5es de outras institui\u00e7\u00f5es e empresas.<\/p>\n<p>Uma das propostas do Facebook \u00e9 proibir o impulsionamento de postagens 48 horas antes e at\u00e9 24 horas depois da elei\u00e7\u00e3o. A empresa argumenta que a responsabilidade por verificar o cumprimento desse prazo deve ser apenas do anunciante, ou seja, candidatos, partidos, coliga\u00e7\u00f5es ou federa\u00e7\u00f5es. O texto da minuta que a plataforma sugere alterar determina que cabe \u201cao provedor de aplica\u00e7\u00e3o, que comercializa o impulsionamento, realizar o desligamento da veicula\u00e7\u00e3o de propaganda eleitoral\u201d nos per\u00edodos em que seja proibida.<\/p>\n<p>O Facebook tamb\u00e9m prop\u00f4s substituir \u201cresponsabilidade\u201d por \u201cdever\u201d em um artigo que estabelece que \u00e9 \u201cresponsabilidade\u201d das plataformas \u201ca ado\u00e7\u00e3o e publiciza\u00e7\u00e3o de medidas para impedir ou diminuir a circula\u00e7\u00e3o de conte\u00fado il\u00edcito que atinja a integridade do processo eleitoral\u201d. Essa lista inclui, por exemplo, ataques \u00e0s urnas eletr\u00f4nicas.<\/p>\n<p>Com informa\u00e7\u00f5es de O Globo.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/tse-analisa-acordo-entre-big-techs-para-combater-fake-news-geradas-por-ia-nas-eleicoes\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reprodu\u00e7\u00e3o. Na Confer\u00eancia de Seguran\u00e7a de Munique, realizada na Alemanha nesta sexta-feira (16), 20 empresas l\u00edderes de tecnologia, incluindo Adobe, Amazon, Google, IBM, Meta, Microsoft, OpenAI, TikTok e X (antigo Twitter), uniram for\u00e7as para enfrentar o desafio das fake news geradas por intelig\u00eancia artificial (IA) durante as elei\u00e7\u00f5es de 2024. O objetivo \u00e9 prevenir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[985,984,986,988,992,970,989,991,40,990,18,192,987,983],"class_list":["post-539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-acordo","tag-analisa","tag-big","tag-combater","tag-eleicoes","tag-entre","tag-fake","tag-geradas","tag-nas","tag-news","tag-para","tag-por","tag-techs","tag-tse"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=539"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/539\/revisions"}],"predecessor-version":[{"id":541,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/539\/revisions\/541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/540"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}