{"id":536,"date":"2024-02-17T22:12:01","date_gmt":"2024-02-17T22:12:01","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/17\/secretario-de-seguranca-de-sao-paulo-critica-saidinhas-bandido-visto-como-vitima\/"},"modified":"2024-02-18T00:29:38","modified_gmt":"2024-02-18T00:29:38","slug":"secretario-de-seguranca-de-sao-paulo-critica-saidinhas-bandido-visto-como-vitima","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/17\/secretario-de-seguranca-de-sao-paulo-critica-saidinhas-bandido-visto-como-vitima\/","title":{"rendered":"Secret\u00e1rio de Seguran\u00e7a de S\u00e3o Paulo critica saidinhas: \u201cBandido visto como v\u00edtima\u201d"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: Reprodu\u00e7\u00e3o.<\/p>\n<p>Guilherme Derrite, Secret\u00e1rio de Seguran\u00e7a P\u00fablica do Estado de S\u00e3o Paulo, expressou em um artigo para o jornal O Estado de S. Paulo suas preocupa\u00e7\u00f5es sobre a efic\u00e1cia e os efeitos da sa\u00edda tempor\u00e1ria de presos.<\/p>\n<p>O texto destaca um ataque perpetrado por criminosos contra dois policiais militares na cidade de Santos, no litoral paulista. O cabo Silveira faleceu como resultado do ataque, enquanto o sargento Guilherme perdeu a vis\u00e3o de um olho.<\/p>\n<p>Os agressores eram benefici\u00e1rios do programa de \u201csaidinha\u201d, que autoriza a sa\u00edda tempor\u00e1ria de detentos. Um deles, condenado em 2014, n\u00e3o retornou ap\u00f3s a sua sa\u00edda tempor\u00e1ria em 2017. O outro, condenado a 12 anos em 2020, tamb\u00e9m optou por n\u00e3o voltar ap\u00f3s o per\u00edodo de liberdade tempor\u00e1ria.<\/p>\n<p>Outro incidente envolvendo um preso em sa\u00edda tempor\u00e1ria que n\u00e3o retornou \u00e0 pris\u00e3o aconteceu em Votuporanga, no interior de S\u00e3o Paulo, resultando em um homic\u00eddio.<\/p>\n<p>Derrite questiona o prop\u00f3sito da pris\u00e3o se ela n\u00e3o contribui para a justi\u00e7a \u00e0s v\u00edtimas nem imp\u00f5e custos aos criminosos. Ele sugere que a pris\u00e3o parece servir apenas \u00e0 ressocializa\u00e7\u00e3o do criminoso, em uma invers\u00e3o de pap\u00e9is onde o bandido \u00e9 retratado como a verdadeira v\u00edtima da sociedade.<\/p>\n<p>O secret\u00e1rio tamb\u00e9m critica um grupo de trabalho que inclui membros do Minist\u00e9rio P\u00fablico Federal, os quais ele descreve como populistas, por considerarem discutir o fim das sa\u00eddas tempor\u00e1rias.<\/p>\n<p>Ele destaca que cerca de 35 mil detentos deixaram os pres\u00eddios paulistas e 1,5 mil n\u00e3o retornaram. Embora o n\u00famero represente apenas 5% dos benefici\u00e1rios, ele ressalta que, ao longo de um ano, isso equivale a 6 mil condenados nas ruas, cometendo novos crimes.<\/p>\n<p>Com informa\u00e7\u00f5es do Pleno News.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/secretario-de-seguranca-de-sao-paulo-critica-saidinhas-bandido-visto-como-vitima\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reprodu\u00e7\u00e3o. Guilherme Derrite, Secret\u00e1rio de Seguran\u00e7a P\u00fablica do Estado de S\u00e3o Paulo, expressou em um artigo para o jornal O Estado de S. Paulo suas preocupa\u00e7\u00f5es sobre a efic\u00e1cia e os efeitos da sa\u00edda tempor\u00e1ria de presos. O texto destaca um ataque perpetrado por criminosos contra dois policiais militares na cidade de Santos, no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[980,61,978,729,979,5,977,427,981,982],"class_list":["post-536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-bandido","tag-como","tag-critica","tag-paulo","tag-saidinhas","tag-sao","tag-secretario","tag-seguranca","tag-visto","tag-vitima"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=536"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/536\/revisions"}],"predecessor-version":[{"id":538,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/536\/revisions\/538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/537"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}