{"id":491,"date":"2024-02-16T23:17:14","date_gmt":"2024-02-16T23:17:14","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/16\/sindrome-do-pescoco-de-texto-entenda-o-problema-causado-pelo-uso-do-celular\/"},"modified":"2024-02-17T04:34:52","modified_gmt":"2024-02-17T04:34:52","slug":"sindrome-do-pescoco-de-texto-entenda-o-problema-causado-pelo-uso-do-celular","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/16\/sindrome-do-pescoco-de-texto-entenda-o-problema-causado-pelo-uso-do-celular\/","title":{"rendered":"S\u00edndrome do pesco\u00e7o de texto: entenda o problema causado pelo uso do celular"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>\u00a0Foto: (Cast Of Thousands | Shutterstock)<\/p>\n<h2 class=\"wp-block-heading\">Fisioterapeuta explica como a dor causada pelo uso do smartphone pode afetar a sa\u00fade do corpo<\/h2>\n<p>A chegada dos smartphones revolucionou a vida dos seres humanos. \u00c9 ineg\u00e1vel que com tantas utilidades e possibilidades eles tenham se tornado nosso fiel companheiro, estando conosco o tempo todo, inclusive nas atividades em que eles n\u00e3o precisam estar. Por isso, est\u00e1 cada vez mais comum as pessoas serem diagnosticadas com a s\u00edndrome do pesco\u00e7o de texto.<\/p>\n<p>Essa s\u00edndrome, tamb\u00e9m conhecida como text neck (em ingl\u00eas), de acordo com o fisioterapeuta Bernardo Sampaio, \u00e9 caracterizada pela sobrecarga da musculatura do pesco\u00e7o, exatamente o que as pessoas costumam fazer ao longo do dia, passando horas com a cabe\u00e7a inclinada para baixo olhando para a tela do celular.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Sintomas mais comuns<\/strong><\/h2>\n<p>Conforme explica o especialista, dentre os principais<strong>\u00a0sintomas<\/strong>\u00a0dessa s\u00edndrome est\u00e3o as \u201cdores na regi\u00e3o do pesco\u00e7o que podem come\u00e7ar a descer para os ombros\u201d, al\u00e9m de dores de cabe\u00e7a, sensa\u00e7\u00e3o de peso nos ombros e coluna desalinhada.<\/p>\n<figure class=\"wp-block-image size-full\"><picture decoding=\"async\" class=\"wp-image-105109\"><source type=\"image\/webp\" srcset=\"https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/02\/IMG_6933.jpeg.webp 564w, https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/02\/IMG_6933-300x199.jpeg.webp 300w\" sizes=\"(max-width: 564px) 100vw, 564px\"\/><\/picture><figcaption class=\"wp-element-caption\">Movimentar o pesco\u00e7o ajuda a evitar a s\u00edndrome (Imagem: Vasily Gureev | Shutterstock)\u00a0<\/figcaption><\/figure>\n<h2 class=\"wp-block-heading\"><strong>Preven\u00e7\u00e3o e tratamento<\/strong><\/h2>\n<p>Bernardo Sampaio alerta que \u00e9 importante se precaver e tratar essa\u00a0<strong>s\u00edndrome<\/strong>\u00a0ainda no come\u00e7o, para n\u00e3o haver preju\u00edzos \u00e0 sa\u00fade do corpo no futuro. \u201cPara isso, podemos come\u00e7ar diminuindo o tempo que gastamos no celular e tablet, e quando formos utiliz\u00e1-los \u00e9 interessante sempre movimentar a cabe\u00e7a, soltar o pesco\u00e7o e permanecer em posi\u00e7\u00e3o confort\u00e1vel\u201d, recomenda.<\/p>\n<p>Existem alguns exerc\u00edcios que podem ser feitos a fim de evitar ou diminuir a dor causada pelo text neck, \u201ccomo movimentar a cabe\u00e7a, fazendo meia-lua, e depois girando-a em uma volta completa ou alongar a regi\u00e3o do trap\u00e9zio, inclinando a cabe\u00e7a, e com o aux\u00edlio da m\u00e3o, puxando levemente para baixo\u201d, ensina o fisioterapeuta.<\/p>\n<h2 class=\"wp-block-heading\"><strong>O que dizem as pesquisas?<\/strong><\/h2>\n<p>V\u00e1rios estudos est\u00e3o sendo realizados para saber o qu\u00e3o grave essa s\u00edndrome pode ser e de quais maneiras ela pode afetar a\u00a0<strong>qualidade de vida.<\/strong>\u00a0Alguns deles apontam que a longo prazo o text neck pode chegar a causar les\u00f5es na coluna cervical. No entanto, pesquisas continuam sendo realizadas para confirmar essa informa\u00e7\u00e3o.\u00a0<\/p>\n<p>Al\u00e9m disso, o uso de smartphones ainda \u00e9 recente e, por esse motivo, \u00e9 necess\u00e1rio continuar avaliando o assunto ao longo dos anos para podermos ter certeza sobre como isso pode afetar as pessoas futuramente.<\/p>\n<p>O Tempo <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/sindrome-do-pescoco-de-texto-entenda-o-problema-causado-pelo-uso-do-celular\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Foto: (Cast Of Thousands | Shutterstock) Fisioterapeuta explica como a dor causada pelo uso do smartphone pode afetar a sa\u00fade do corpo A chegada dos smartphones revolucionou a vida dos seres humanos. \u00c9 ineg\u00e1vel que com tantas utilidades e possibilidades eles tenham se tornado nosso fiel companheiro, estando conosco o tempo todo, inclusive nas atividades [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[904,906,116,417,901,903,900,902,905],"class_list":["post-491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-causado","tag-celular","tag-entenda","tag-pelo","tag-pescoco","tag-problema","tag-sindrome","tag-texto","tag-uso"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=491"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/491\/revisions"}],"predecessor-version":[{"id":493,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/491\/revisions\/493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/492"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}