{"id":476,"date":"2024-02-16T22:24:05","date_gmt":"2024-02-16T22:24:05","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/16\/ministerio-da-justica-prorroga-suspensao-de-banho-de-sol-visitas-e-outras-restricoes-em-presidios-federais\/"},"modified":"2024-02-16T22:37:02","modified_gmt":"2024-02-16T22:37:02","slug":"ministerio-da-justica-prorroga-suspensao-de-banho-de-sol-visitas-e-outras-restricoes-em-presidios-federais","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/16\/ministerio-da-justica-prorroga-suspensao-de-banho-de-sol-visitas-e-outras-restricoes-em-presidios-federais\/","title":{"rendered":"Minist\u00e9rio da Justi\u00e7a prorroga suspens\u00e3o de banho de sol, visitas e outras restri\u00e7\u00f5es em pres\u00eddios federais"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: Reprodu\u00e7\u00e3o<\/p>\n<p>O Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica prorrogou as restri\u00e7\u00f5es em pres\u00eddios federais at\u00e9 a pr\u00f3xima quarta-feira (21). A medida, que tem validade a partir deste s\u00e1bado (17), suspende banhos de sol, visitas sociais e atividades educionais, de trabalho e religiosas.<\/p>\n<p>A portaria que estabelece as restri\u00e7\u00f5es no per\u00edodo foi publicada nesta sexta-feira (16) pela Secretaria Nacional de Pol\u00edticas Penais (Senappen), do Minist\u00e9rio da Justi\u00e7a.<\/p>\n<p>O texto da portaria tamb\u00e9m limita o acesso \u00e0s depend\u00eancias do pres\u00eddio que s\u00e3o destinadas a \u201cviv\u00eancias, isolamento e inclus\u00e3o\u201d. O acesso a atendimento m\u00e9dico, aos advogados e ao cumprimento de decis\u00f5es judiciais est\u00e3o mantidos.<\/p>\n<p>As medidas foram tomadas em desdobramento \u00e0 primeira fuga registrada no sistema penitenci\u00e1rio federal. Na \u00faltima quarta-feira (14), dois apenados conseguiram escapar da pris\u00e3o de seguran\u00e7a m\u00e1xima de Mossor\u00f3 e, at\u00e9 o momento, n\u00e3o foram capturados.<\/p>\n<p>Os dois fugitivos s\u00e3o Rog\u00e9rio da Silva Mendon\u00e7a, de 35 anos, e Deibson Cabral Nascimento, de 33 anos, ligados \u00e0 fac\u00e7\u00e3o criminosa Comando Vermelho.<\/p>\n<p><strong>Procura<\/strong><\/p>\n<p>Helic\u00f3pteros, drones e cerca de 300 policias atuam para capturar os suspeitos. Na madrugada desta sexta-feira, agentes federais e policiais militares do Rio Grande do Norte encontraram rastros que apontam para a rota de fuga dos detentos que fugiram do pres\u00eddio federal de Mossor\u00f3.<\/p>\n<p>Conforme informado pelo 2\u00ba Batalh\u00e3o da Pol\u00edcia Militar (2 BPM), foram encontradas duas camisas, uma rede e rastros de sapatilhas, semelhantes as usadas pelos internos no pres\u00eddio federal.<\/p>\n<p>O rastro, segundo o 2\u00ba BPM, foi encontrado nas imedia\u00e7\u00f5es da Serra Mossor\u00f3, que tamb\u00e9m est\u00e1 pr\u00f3xima da localidade de Rancho da Ca\u00e7a, onde uma casa foi furtada na manh\u00e3 da \u00faltima quinta-feira (crime do qual os foragidos s\u00e3o suspeitos).<\/p>\n<p>N\u00e3o h\u00e1, at\u00e9 a publica\u00e7\u00e3o desta mat\u00e9ria, a constata\u00e7\u00e3o de que o rastro pertence a Rog\u00e9rio da Silva e Deibson Cabral. Por\u00e9m, o resultado da dilig\u00eancia pode corroborar com a hip\u00f3tese das for\u00e7as federais, a qual conclui que os criminosos permanecem se deslocando nas imedia\u00e7\u00f5es da cidade do Oeste potiguar.<\/p>\n<p>Segundo o ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Ricardo Lewandowski, as autoridades acreditam que os fugitivos est\u00e3o em um per\u00edmetro de 15 quil\u00f4metros de dist\u00e2ncia do pres\u00eddio, na zona rural.<\/p>\n<p>Tribuna do Norte<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/ministerio-da-justica-prorroga-suspensao-de-banho-de-sol-visitas-e-outras-restricoes-em-presidios-federais\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reprodu\u00e7\u00e3o O Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica prorrogou as restri\u00e7\u00f5es em pres\u00eddios federais at\u00e9 a pr\u00f3xima quarta-feira (21). A medida, que tem validade a partir deste s\u00e1bado (17), suspende banhos de sol, visitas sociais e atividades educionais, de trabalho e religiosas. A portaria que estabelece as restri\u00e7\u00f5es no per\u00edodo foi publicada nesta sexta-feira [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[875,880,872,369,877,879,873,878,534,874,876],"class_list":["post-476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-banho","tag-federais","tag-justica","tag-ministerio","tag-outras","tag-presidios","tag-prorroga","tag-restricoes","tag-sol","tag-suspensao","tag-visitas"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/476\/revisions"}],"predecessor-version":[{"id":478,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/476\/revisions\/478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/477"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}