{"id":473,"date":"2024-02-16T20:32:37","date_gmt":"2024-02-16T20:32:37","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/16\/agora-juiz-decide-que-donald-trump-tera-que-pagar-multa-de-r-176-bilhao-entenda\/"},"modified":"2024-02-16T20:57:10","modified_gmt":"2024-02-16T20:57:10","slug":"agora-juiz-decide-que-donald-trump-tera-que-pagar-multa-de-r-176-bilhao-entenda","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/16\/agora-juiz-decide-que-donald-trump-tera-que-pagar-multa-de-r-176-bilhao-entenda\/","title":{"rendered":"AGORA: Juiz decide que Donald Trump ter\u00e1 que pagar multa de R$ 1,76 bilh\u00e3o; entenda"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: REUTERS\/Andrew Kelly\/Pool\/File Photo\u00a0<\/p>\n<h2 class=\"wp-block-heading\">A procuradora-geral do estado de Nova York processou Trump em setembro de 2022 por mentir durante uma d\u00e9cada sobre os valores de ativos da sua empresa do setor imobili\u00e1rio para obter melhores condi\u00e7\u00f5es em empr\u00e9stimos banc\u00e1rios e seguros.<\/h2>\n<p>O juiz Arthur Engoron, de Nova York, decidiu nesta sexta-feira (16) que o ex-presidente dos\u00a0Estados Unidos\u00a0Donald Trump\u00a0dever\u00e1 pagar uma multa de US$ 354,9 milh\u00f5es (R$ 1,76 bilh\u00e3o)\u00a0<strong>por inflar os n\u00fameros do balan\u00e7o financeiro de sua empresa. Al\u00e9m disso, ele est\u00e1 proibido de fazer neg\u00f3cios no estado de Nova York por tr\u00eas anos.\u00a0<\/strong><\/p>\n<p>A procuradora-geral do estado, Letitia James, processou Trump e a Organiza\u00e7\u00e3o Trump em setembro de 2022\u00a0por mentirem durante uma d\u00e9cada sobre valores de ativos e seu patrim\u00f4nio l\u00edquido para obter melhores condi\u00e7\u00f5es em empr\u00e9stimos banc\u00e1rios e seguros.<\/p>\n<p>Ela disse que o ex-presidente dos EUA inflou o seu patrim\u00f4nio l\u00edquido em at\u00e9 U$ 2,23 bilh\u00f5es (R$ 11,9 bilh\u00f5es) nas demonstra\u00e7\u00f5es financeiras anuais fornecidas a bancos e seguradoras.\u00a0<\/p>\n<p>Letitia disse que os ativos cujos valores foram inflacionados inclu\u00edam a propriedade de Trump em Mar-a-Lago, na Fl\u00f3rida, seu apartamento de cobertura na Trump Tower, em Manhattan, e v\u00e1rios edif\u00edcios de escrit\u00f3rios e campos de golfe.\u00a0<\/p>\n<p>O valor a ser pago por Trump foi pedido por Letitia, que tamb\u00e9m solicitou a proibi\u00e7\u00e3o de Trump de fazer neg\u00f3cios no estado.\u00a0<\/p>\n<p>Para chegar ao valor da multa, a procuradora-geral calculou da seguinte forma:\u00a0<\/p>\n<ul>\n<li>somou o dinheiro que supostamente Trump ganhou com a declara\u00e7\u00e3o incorreta de seus ativos;\u00a0<\/li>\n<li>B\u00f4nus pagos aos funcion\u00e1rios da Organiza\u00e7\u00e3o Trump que participaram do esquema;<\/li>\n<li>E lucro obtido de forma fraudulenta em dois neg\u00f3cios imobili\u00e1rios.<\/li>\n<\/ul>\n<p>Especialistas ouvidos pela BBC afirmaram<strong>que o valor \u00e9 t\u00e3o alto que pode impactar os neg\u00f3cios e as finan\u00e7as de Trump.\u00a0<\/strong>O ex-presidente tem uma empresa do mercado imobili\u00e1rio.\u00a0<\/p>\n<p>Segundo a lista da Forbes, a fortuna de Donald Trump \u00e9 estimada em US$ 2,6 bilh\u00f5es (ou R$ 12,93 bilh\u00f5es).\u00a0<\/p>\n<p>O ex-presidente dos Estados Unidos Donald Trump enfrenta quatro processos criminais nos quais \u00e9 r\u00e9u. Em um deles,\u00a0o do caso Stormy Daniels, teve data marcada para o julgamento no fim de mar\u00e7o..\u00a0Entre 2015 e 2017, ele pagou dinheiro para a atriz porn\u00f4 para que ela n\u00e3o desse entrevista e, depois disso, falsificou os registros cont\u00e1veis desses pagamentos.\u00a0<\/p>\n<p>Trump se declara inocente e afirma que o promotor Alvin Bragg, que \u00e9 do Partido Democrata e foi quem o processou criminalmente, tem apenas fins eleitoreiros.\u00a0<\/p>\n<p>Com isso, Donald Trump ser\u00e1 o primeiro ex-presidente da hist\u00f3ria dos EUA a enfrentar um julgamento criminal.\u00a0<\/p>\n<p>O processo contra o ex-presidente come\u00e7ou ap\u00f3s ter sido descoberto um pagamento de US$ 130 mil \u00e0 atriz porn\u00f4 Stormy Daniels \u00e0s v\u00e9speras da elei\u00e7\u00e3o presidencial de 2016. Trump queria impedir que ela falasse para uma revista que os dois tiveram um caso.\u00a0<\/p>\n<p>O promotor afirma que quem desembolsou os US$ 130 mil d\u00f3lares pagos a Stormy Daniels foi o ent\u00e3o advogado de Trump, Michael Cohen, e que o dinheiro foi registrado contabilmente como um pagamento aos servi\u00e7os jur\u00eddicos de Cohen, e n\u00e3o como um desembolso feito para \u201ccomprar o sil\u00eancio\u201d da atriz porn\u00f4.\u00a0<\/p>\n<p>A Promotoria afirma que, de agosto de 2015 a dezembro de 2017, Trump organizou um esquema para influenciar a elei\u00e7\u00e3o de 2016 que consistia em identificar e comprar informa\u00e7\u00f5es negativas sobre ele para impedir que fossem publicadas.<\/p>\n<p>g1<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/agora-juiz-decide-que-donald-trump-tera-que-pagar-multa-de-r-176-bilhao-entenda\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: REUTERS\/Andrew Kelly\/Pool\/File Photo\u00a0 A procuradora-geral do estado de Nova York processou Trump em setembro de 2022 por mentir durante uma d\u00e9cada sobre os valores de ativos da sua empresa do setor imobili\u00e1rio para obter melhores condi\u00e7\u00f5es em empr\u00e9stimos banc\u00e1rios e seguros. O juiz Arthur Engoron, de Nova York, decidiu nesta sexta-feira (16) que o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[43,871,446,869,116,868,870,819,147,604],"class_list":["post-473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-agora","tag-bilhao","tag-decide","tag-donald","tag-entenda","tag-juiz","tag-multa","tag-pagar","tag-tera","tag-trump"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=473"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/473\/revisions"}],"predecessor-version":[{"id":475,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/473\/revisions\/475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/474"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}