{"id":447,"date":"2024-02-16T10:47:00","date_gmt":"2024-02-16T10:47:00","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/16\/reforco-no-muro-do-presidio-de-brasilia-custou-mais-caro-do-que-a-construcao-de-todo-o-complexo\/"},"modified":"2024-02-16T10:54:41","modified_gmt":"2024-02-16T10:54:41","slug":"reforco-no-muro-do-presidio-de-brasilia-custou-mais-caro-do-que-a-construcao-de-todo-o-complexo","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/16\/reforco-no-muro-do-presidio-de-brasilia-custou-mais-caro-do-que-a-construcao-de-todo-o-complexo\/","title":{"rendered":"Refor\u00e7o no muro do pres\u00eddio de Bras\u00edlia custou mais caro do que a constru\u00e7\u00e3o de todo o complexo"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>A constru\u00e7\u00e3o de muralhas nos quatro pres\u00eddios federais desprotegidos n\u00e3o \u00e9 uma ideia nova, conforme comunicados, not\u00edcias e informes da Secretaria Nacional de Pol\u00edticas Penais indicam.<\/p>\n<p>Em 29 de junho de 2022, o site da Secretaria divulgou uma s\u00e9rie de investimentos destinados \u00e0 moderniza\u00e7\u00e3o do sistema prisional federal, incluindo o \u2018Projeto Muralha\u2019. O comunicado destacou um investimento de aproximadamente R$ 70 milh\u00f5es na constru\u00e7\u00e3o da muralha para a Penitenci\u00e1ria Federal em Bras\u00edlia.<\/p>\n<p>A inaugura\u00e7\u00e3o da muralha ocorreu em novembro do mesmo ano, conforme evidenciado em um v\u00eddeo divulgado no canal do YouTube da Secretaria Nacional de Pol\u00edticas Penais. No v\u00eddeo, o governo anunciou que planejava construir muralhas e torres de seguran\u00e7a em todas as unidades prisionais administradas pelo Depen, localizadas em Catanduvas (PR), Campo Grande (MS), Mossor\u00f3 (RN) e Porto Velho (RO). A \u00faltima j\u00e1 estava programada para receber a pr\u00f3xima muralha.<\/p>\n<p>O custo da muralha em Bras\u00edlia, R$ 70 milh\u00f5es, representou quase o dobro do investimento destinado \u00e0 constru\u00e7\u00e3o do pres\u00eddio como um todo, que totalizou R$ 45 milh\u00f5es \u2013 uma diferen\u00e7a de 75%. Ajustando os c\u00e1lculos \u00e0 infla\u00e7\u00e3o, a disparidade de custos seria de 32%. Vale destacar que as obras da pris\u00e3o foram conclu\u00eddas com tr\u00eas anos de atraso.<\/p>\n<p><em>Com informa\u00e7\u00f5es de CNN Brasil<\/em><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/reforco-no-muro-do-presidio-de-brasilia-custou-mais-caro-do-que-a-construcao-de-todo-o-complexo\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A constru\u00e7\u00e3o de muralhas nos quatro pres\u00eddios federais desprotegidos n\u00e3o \u00e9 uma ideia nova, conforme comunicados, not\u00edcias e informes da Secretaria Nacional de Pol\u00edticas Penais indicam. Em 29 de junho de 2022, o site da Secretaria divulgou uma s\u00e9rie de investimentos destinados \u00e0 moderniza\u00e7\u00e3o do sistema prisional federal, incluindo o \u2018Projeto Muralha\u2019. O comunicado destacou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[827,829,830,153,828,91,826,706,825,85],"class_list":["post-447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-brasilia","tag-caro","tag-complexo","tag-construcao","tag-custou","tag-mais","tag-muro","tag-presidio","tag-reforco","tag-todo"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=447"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/447\/revisions"}],"predecessor-version":[{"id":449,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/447\/revisions\/449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/448"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}