{"id":43,"date":"2024-01-28T22:17:56","date_gmt":"2024-01-28T22:17:56","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/01\/28\/hackers-ligados-a-coreia-do-norte-batem-recorde-de-ataques-aponta-relatorio-veja-numeros\/"},"modified":"2024-01-29T07:47:05","modified_gmt":"2024-01-29T07:47:05","slug":"hackers-ligados-a-coreia-do-norte-batem-recorde-de-ataques-aponta-relatorio-veja-numeros","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/01\/28\/hackers-ligados-a-coreia-do-norte-batem-recorde-de-ataques-aponta-relatorio-veja-numeros\/","title":{"rendered":"Hackers ligados \u00e0 Coreia do Norte batem recorde de ataques, aponta relat\u00f3rio; Veja n\u00fameros"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>De acordo com um relat\u00f3rio da empresa de an\u00e1lise de blockchain Chainalysis, hackers vinculados \u00e0 Coreia do Norte realizaram um n\u00famero recorde de 20 ataques a plataformas de criptografia em 2023. Apesar do aumento nas tentativas de invas\u00e3o, houve uma redu\u00e7\u00e3o no valor total dos criptoativos roubados em compara\u00e7\u00e3o com 2022, passando de US$ 1,7 bilh\u00e3o para US$ 1 bilh\u00e3o (R$ 5 bilh\u00f5es) no ano passado.<\/p>\n<figure class=\"wp-block-image size-full\"><picture decoding=\"async\" class=\"wp-image-99365\"><source type=\"image\/webp\" srcset=\"https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/01\/image-487.png.webp 640w, https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/01\/image-487-300x206.png.webp 300w\" sizes=\"(max-width: 640px) 100vw, 640px\"\/><\/picture><figcaption class=\"wp-element-caption\">Foto: Chainalysis.<\/figcaption><\/figure>\n<p>Os hackers, que operam em conjunto com os grupos de espionagem Kimsuky e Lazarus Group, empregam diversas t\u00e1ticas maliciosas para obter grandes quantidades de criptoativos. Outro relat\u00f3rio da empresa de intelig\u00eancia TRM Labs estima que esses hackers associados \u00e0 Coreia do Norte conseguiram roubar US$ 600 milh\u00f5es em 2023.<\/p>\n<figure class=\"wp-block-image size-full\"><picture decoding=\"async\" class=\"wp-image-99366\"><source type=\"image\/webp\" srcset=\"https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/01\/image-488.png.webp 640w, https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/01\/image-488-300x206.png.webp 300w\" sizes=\"(max-width: 640px) 100vw, 640px\"\/><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"440\" src=\"https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/01\/image-488.png\" alt=\"\" srcset=\"https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/01\/image-488.png 640w, https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/01\/image-488-300x206.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\"\/>\n<\/picture><figcaption class=\"wp-element-caption\">Foto: Reprodu\u00e7\u00e3o\/SBT News.<\/figcaption><\/figure>\n<p>Destaca-se que o Lazarus Group, al\u00e9m dos ataques em larga escala, tamb\u00e9m teria subtra\u00eddo US$ 41 milh\u00f5es em criptoativos de um cassino online e de um site de apostas. O governo dos Estados Unidos, em um relat\u00f3rio, menciona que esse grupo norte-coreano utilizava uma ferramenta de lavagem de dinheiro virtual chamada Sinbad.io, que misturava moedas virtuais para dificultar o rastreamento de transa\u00e7\u00f5es. O FBI interveio e fechou esse servi\u00e7o.<\/p>\n<p>O relat\u00f3rio da Chainalysis sugere ainda que o governo norte-coreano estaria utilizando os recursos provenientes desses crimes cibern\u00e9ticos para financiar seu programa nuclear. O estudo ressalta que a maioria dos especialistas concorda que os ativos roubados est\u00e3o sendo direcionados para sustentar os programas de armas nucleares do pa\u00eds asi\u00e1tico.<\/p>\n<p><strong>Com informa\u00e7\u00f5es do SBT News.<\/strong><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/01\/hackers-ligados-a-coreia-do-norte-batem-recorde-de-ataques-aponta-relatorio-veja-numeros\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com um relat\u00f3rio da empresa de an\u00e1lise de blockchain Chainalysis, hackers vinculados \u00e0 Coreia do Norte realizaram um n\u00famero recorde de 20 ataques a plataformas de criptografia em 2023. Apesar do aumento nas tentativas de invas\u00e3o, houve uma redu\u00e7\u00e3o no valor total dos criptoativos roubados em compara\u00e7\u00e3o com 2022, passando de US$ 1,7 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,1],"tags":[30,21,28,26,24,25,27,32,29,31,11],"class_list":["post-43","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-uncategorized","tag-aponta","tag-ataques","tag-batem","tag-coreia","tag-hackers","tag-ligados","tag-norte","tag-numeros","tag-recorde","tag-relatorio","tag-veja"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/43\/revisions"}],"predecessor-version":[{"id":45,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/43\/revisions\/45"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/44"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=43"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=43"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}