{"id":393,"date":"2024-02-14T23:14:25","date_gmt":"2024-02-14T23:14:25","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/14\/alerta-ciclone-subtropical-intensifica-risco-de-inundacoes-e-quedas-de-arvores-em-13-estados\/"},"modified":"2024-02-15T08:59:55","modified_gmt":"2024-02-15T08:59:55","slug":"alerta-ciclone-subtropical-intensifica-risco-de-inundacoes-e-quedas-de-arvores-em-13-estados","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/14\/alerta-ciclone-subtropical-intensifica-risco-de-inundacoes-e-quedas-de-arvores-em-13-estados\/","title":{"rendered":"ALERTA: Ciclone subtropical intensifica risco de inunda\u00e7\u00f5es e quedas de \u00e1rvores em 13 estados"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>foto: Reprodu\u00e7\u00e3o <\/p>\n<p>O Instituto Nacional de Meteorologia (Inmet) emitiu um alerta laranja nesta quarta-feira (14), destacando o perigo iminente em 13 estados do Brasil. O aviso, que teve in\u00edcio \u00e0s 9h20 do dia 14 e permanecer\u00e1 em vigor at\u00e9 as 3h de quinta-feira (15), abrange \u00e1reas no Acre, Amazonas, Roraima, Amap\u00e1, Par\u00e1, Maranh\u00e3o, Piau\u00ed, Cear\u00e1, Rio de Janeiro, Minas Gerais, S\u00e3o Paulo, Paran\u00e1 e Mato Grosso do Sul.<\/p>\n<p>A classifica\u00e7\u00e3o laranja indica condi\u00e7\u00f5es meteorol\u00f3gicas cr\u00edticas, com previs\u00e3o de chuvas entre 30 e 60 mm\/h ou 50 e 100 mm\/dia, al\u00e9m de ventos intensos, variando entre 60 e 100 km\/h, e possibilidade de queda de granizo. Os riscos associados incluem cortes no fornecimento de energia el\u00e9trica, danos a planta\u00e7\u00f5es, queda de \u00e1rvores e alagamentos.<\/p>\n<p>Para essas regi\u00f5es sob alerta laranja, o Inmet emitiu orienta\u00e7\u00f5es importantes:<\/p>\n<ul>\n<li>Evitar abrigar-se debaixo de \u00e1rvores durante rajadas de vento, devido ao risco de queda e descargas el\u00e9tricas;<\/li>\n<li>N\u00e3o estacionar ve\u00edculos pr\u00f3ximos a torres de transmiss\u00e3o e placas de propaganda;<\/li>\n<li>Desligar aparelhos el\u00e9tricos e quadro geral de energia, sempre que poss\u00edvel;<\/li>\n<li>Buscar informa\u00e7\u00f5es adicionais junto \u00e0 Defesa Civil (telefone 199) e ao Corpo de Bombeiros (telefone 193).<\/li>\n<\/ul>\n<p>Alguns estados tamb\u00e9m est\u00e3o sob alerta amarelo (perigo potencial), totalizando 17 unidades federativas: Rond\u00f4nia, Amazonas, Mato Grosso, Par\u00e1, Tocantins, Maranh\u00e3o, Piau\u00ed, Cear\u00e1, Rio Grande do Norte, Para\u00edba, Pernambuco, Alagoas, Sergipe, Esp\u00edrito Santo, S\u00e3o Paulo, Mato Grosso do Sul e Mato Grosso. O alerta amarelo indica situa\u00e7\u00f5es meteorol\u00f3gicas com potencial perigoso, exigindo cuidado especial em atividades sujeitas a riscos meteorol\u00f3gicos.<\/p>\n<p><strong>Ciclone Subtropical Previsto para os Estados do Rio de Janeiro e S\u00e3o Paulo<\/strong><\/p>\n<p>Al\u00e9m dos alertas, o Inmet reportou a forma\u00e7\u00e3o de um ciclone subtropical em alto-mar, a sudeste de Arraial do Cabo (RJ), com trajet\u00f3ria prevista para leste e, posteriormente, para sul\/sudoeste, a partir da noite desta quarta-feira (14).<\/p>\n<p>O fen\u00f4meno dever\u00e1 ocasionar fortes chuvas no Litoral Norte de S\u00e3o Paulo at\u00e9 a Regi\u00e3o Metropolitana do Rio de Janeiro, com maior impacto previsto na Costa Verde, incluindo os munic\u00edpios de Angra dos Reis e Paraty.<\/p>\n<p>A Marinha do Brasil, em colabora\u00e7\u00e3o com o Centro de Hidrografia da Marinha, o Centro Integrado de Meteorologia Aeron\u00e1utica da For\u00e7a A\u00e9rea Brasileira e o Instituto Nacional de Pesquisas Espaciais (Inpe), confirmou a previs\u00e3o.<\/p>\n<p>Persistindo as condi\u00e7\u00f5es atmosf\u00e9ricas e intensificando-se os ventos, o ciclone pode ser classificado como tempestade subtropical, podendo gerar ventos de at\u00e9 83 km\/h no entorno do ciclone, principalmente nos setores sul e sudeste, at\u00e9 a noite da pr\u00f3xima ter\u00e7a-feira (20).<\/p>\n<p>Gazeta Brasil <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/alerta-ciclone-subtropical-intensifica-risco-de-inundacoes-e-quedas-de-arvores-em-13-estados\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>foto: Reprodu\u00e7\u00e3o O Instituto Nacional de Meteorologia (Inmet) emitiu um alerta laranja nesta quarta-feira (14), destacando o perigo iminente em 13 estados do Brasil. O aviso, que teve in\u00edcio \u00e0s 9h20 do dia 14 e permanecer\u00e1 em vigor at\u00e9 as 3h de quinta-feira (15), abrange \u00e1reas no Acre, Amazonas, Roraima, Amap\u00e1, Par\u00e1, Maranh\u00e3o, Piau\u00ed, Cear\u00e1, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[80,746,741,349,743,744,745,553,742],"class_list":["post-393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-alerta","tag-arvores","tag-ciclone","tag-estados","tag-intensifica","tag-inundacoes","tag-quedas","tag-risco","tag-subtropical"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=393"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/393\/revisions"}],"predecessor-version":[{"id":395,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/393\/revisions\/395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/394"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}