{"id":381,"date":"2024-02-14T23:55:45","date_gmt":"2024-02-14T23:55:45","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/14\/tia-do-goleiro-weverton-morre-apos-acao-da-pm-em-sua-casa\/"},"modified":"2024-02-15T03:41:57","modified_gmt":"2024-02-15T03:41:57","slug":"tia-do-goleiro-weverton-morre-apos-acao-da-pm-em-sua-casa","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/14\/tia-do-goleiro-weverton-morre-apos-acao-da-pm-em-sua-casa\/","title":{"rendered":"Tia do goleiro Weverton morre ap\u00f3s a\u00e7\u00e3o da PM em sua casa"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Divulga\u00e7\u00e3o e Fabio Menotti \/ Ag. Palmeiras<\/p>\n<h2 class=\"wp-block-heading\">Agentes usaram spray de pimenta e prenderam duas filhas da v\u00edtima por desacato<\/h2>\n<p>Maria Jos\u00e9 Pereira, de 67 anos, morreu na \u00faltima ter\u00e7a-feira (13) ap\u00f3s passar mal durante uma a\u00e7\u00e3o da Pol\u00edcia Militar em sua casa, no bairro Pista, em Rio Branco. A idosa era tia do goleiro Weverton, atleta do Palmeiras.<\/p>\n<p>Segundo relato da fam\u00edlia, por volta das 20h30 de quinta-feira (8), agentes da PM invadiram a resid\u00eancia sem mandado, buscando por um dos filhos de Maria Jos\u00e9, primo de Weverton, que est\u00e1 preso h\u00e1 dois anos pelo crime de furto.<\/p>\n<p>Quando a fam\u00edlia explicou que o homem est\u00e1 preso, os policiais usaram spray de pimenta na idosa, nas filhas dela que estavam presentes durante a abordagem e nos netos menores de idade.<\/p>\n<p>Em nota, o Comando-Geral da Pol\u00edcia Militar prestou condol\u00eancias \u00e0 fam\u00edlia e informou a instaura\u00e7\u00e3o de Inqu\u00e9rito Policial Militar (IPM) para apurar a conduta dos policiais envolvidos.<\/p>\n<p>A OAB do Acre publicou uma nota de rep\u00fadio \u00e0 agress\u00e3o sofrida tamb\u00e9m pela advogada da fam\u00edlia, que foi empurrada e teve acesso aos clientes impedido na Delegacia de Flagrantes.<\/p>\n<h2 class=\"wp-block-heading\">O momento das pris\u00f5es<\/h2>\n<p>\u00c0\u00a0<strong>CNN<\/strong>, a advogada Helane Christina, que representa a fam\u00edlia de Maria Jos\u00e9, contou que os agentes da PM chegaram na casa usando uma linguagem agressiva e procuraram motivo para multar a moto de uma das filhas da idosa, que havia chegado na casa durante a abordagem.<\/p>\n<p>\u201cQuando os agentes foram embora, Maria Jos\u00e9, que sofria de problemas card\u00edacos, j\u00e1 estava passando mal, e uma das filhas gritou com os policiais. Eles pararam o carro e voltaram de forma descontrolada e agressiva. As irm\u00e3s correram para dentro da casa, mas eles entraram na sala e prenderam as duas. Uma delas est\u00e1 cheia de hematomas\u201d, conta a advogada, que foi chamada na Delegacia de Flagrantes ap\u00f3s as pris\u00f5es por desacato.<\/p>\n<figure class=\"wp-block-image size-full\"><\/figure>\n<p>Tia do goleiro Weverton morre ap\u00f3s a\u00e7\u00e3o da PM em sua casa no Acre. Imagem mostra a\u00e7\u00e3o dps PMs \/ Reprodu\u00e7\u00e3o<\/p>\n<p>\u201cElas foram presas, e isso \u00e9 tudo o que aconteceu. A m\u00e3e estava ali o tempo todo, segurando a cintura de uma das filhas, implorando para que ele n\u00e3o as levasse\u201d, continuou a advogada, se referindo a imagens do momento da a\u00e7\u00e3o.<\/p>\n<p>A advogada tamb\u00e9m ressaltou que o crime de desacato n\u00e3o justifica a invas\u00e3o de domic\u00edlio, previsto no artigo 5\u00ba da Constitui\u00e7\u00e3o Federal. Ela conta que depois da abordagem, os familiares que ficaram na casa chamaram o SAMU para Maria Jos\u00e9, que foi conduzida para o pronto-socorro da cidade de Rio Branco.<\/p>\n<p>A idosa ficou internada por seis dias, at\u00e9 \u00e0s 5 horas da manh\u00e3 do dia 13, quando teve um princ\u00edpio de infarto por ac\u00famulo de \u00e1gua no pulm\u00e3o. Mesmo ap\u00f3s ser estabilizada, sofreu uma parada card\u00edaca e veio a \u00f3bito.<\/p>\n<p>Outro v\u00eddeo mostra Helane Christina chegando na delegacia na noite da confus\u00e3o e sendo empurrada pelo mesmo policial que realizou as pris\u00f5es, o Sargento Manoel Ribeiro do Nascimento Neto. Ele tentava impedir que a mulher chegasse at\u00e9 as clientes.<\/p>\n<p>\u201cA Comiss\u00e3o da Mulher Advogada entende que se trata de um caso de misoginia e repudia qualquer excesso de ordem f\u00edsica em face da advocacia, [\u2026] notadamente as advogadas criminalistas que convivem diariamente com situa\u00e7\u00f5es hostis quanto ao g\u00eanero\u201d, diz a nota de rep\u00fadio da OAB.<\/p>\n<p>A\u00a0<strong>CNN<\/strong>\u00a0tentou contato com a assessoria do jogador Weverton, mas n\u00e3o obteve retorno at\u00e9 a publica\u00e7\u00e3o desta reportagem.<\/p>\n<p>CNN<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/tia-do-goleiro-weverton-morre-apos-acao-da-pm-em-sua-casa\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Divulga\u00e7\u00e3o e Fabio Menotti \/ Ag. Palmeiras Agentes usaram spray de pimenta e prenderam duas filhas da v\u00edtima por desacato Maria Jos\u00e9 Pereira, de 67 anos, morreu na \u00faltima ter\u00e7a-feira (13) ap\u00f3s passar mal durante uma a\u00e7\u00e3o da Pol\u00edcia Militar em sua casa, no bairro Pista, em Rio Branco. A idosa era tia do goleiro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[722,7,174,720,420,678,719,721],"class_list":["post-381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-acao","tag-apos","tag-casa","tag-goleiro","tag-morre","tag-sua","tag-tia","tag-weverton"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=381"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/381\/revisions"}],"predecessor-version":[{"id":383,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/381\/revisions\/383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/382"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}