{"id":378,"date":"2024-02-15T00:02:12","date_gmt":"2024-02-15T00:02:12","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/15\/stf-forma-maioria-para-tornar-reus-oficiais-que-chefiavam-pm-no-8-1-veja-quem-sao-os-denunciados\/"},"modified":"2024-02-15T02:21:55","modified_gmt":"2024-02-15T02:21:55","slug":"stf-forma-maioria-para-tornar-reus-oficiais-que-chefiavam-pm-no-8-1-veja-quem-sao-os-denunciados","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/15\/stf-forma-maioria-para-tornar-reus-oficiais-que-chefiavam-pm-no-8-1-veja-quem-sao-os-denunciados\/","title":{"rendered":"STF forma maioria para tornar r\u00e9us oficiais que chefiavam PM no 8\/1; veja quem s\u00e3o os denunciados"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>foto: metr\u00f3poles <\/p>\n<h2 class=\"wp-block-heading\">Dois ex-comandantes-gerais da PMDF e outros cinco policiais militares que atuaram durante as invas\u00f5es do 8 de janeiro foram acusados<\/h2>\n<p>A Primeira Turma do Supremo Tribunal Federal (STF) formou maioria para aceitar a den\u00fancia da Procuradoria-Geral da Rep\u00fablica (PGR) e tornar r\u00e9us sete oficiais que integravam a c\u00fapula da Pol\u00edcia Militar do Distrito Federal (PMDF) \u00e0 \u00e9poca dos atos antidemocr\u00e1ticos de 8 de janeiro.<\/p>\n<p>No julgamento virtual, que come\u00e7ou na \u00faltima sexta-feira (9\/2), tr\u00eas dos quatro ministros da Primeira Turma j\u00e1 votaram.<\/p>\n<p>O relator,\u00a0ministro Alexandre de Moraes disse, em seu voto, que a omiss\u00e3o impr\u00f3pria pela qual os oficiais s\u00e3o acusados possibilitou a execu\u00e7\u00e3o dos atentados contra as sedes dos Tr\u00eas Poderes.<\/p>\n<p><strong>Os denunciados s\u00e3o:<\/strong><\/p>\n<ul>\n<li>coronel F\u00e1bio Augusto Vieira: era comandante-geral da PMDF no dia 8 de janeiro;<\/li>\n<li>coronel Klepter Rosa Gon\u00e7alves: era subcomandante da PMDF no dia 8 de janeiro e foi nomeado para o cargo de comandante-geral em 15 de fevereiro;<\/li>\n<li>coronel Jorge Eduardo Naime Barreto: era comandante do Departamento de Opera\u00e7\u00f5es em 8 de janeiro, mas tirou licen\u00e7a do cargo em 3 de janeiro;<\/li>\n<li>coronel Paulo Jos\u00e9 Ferreira de Sousa Bezerra: estava no comando do Departamento de Opera\u00e7\u00f5es no lugar de Naime em 8 de janeiro;<\/li>\n<li>coronel Marcelo Casimiro Vasconcelos Rodrigues: era chefe do 1\u00ba Comando de Policiamento Regional da PMDF em 8 de janeiro;<\/li>\n<li>major Fl\u00e1vio Silvestre de Alencar: atuou no dia 8 de janeiro; e<\/li>\n<li>tenente Rafael Pereira Martins: atuou no dia 8 de janeiro.<\/li>\n<\/ul>\n<p>Segundo a den\u00fancia da PGR, havia \u201cuma profunda contamina\u00e7\u00e3o ideol\u00f3gica de parte dos oficiais da PMDF denunciados, que se mostraram adeptos de teorias conspirat\u00f3rias sobre fraudes eleitorais e de teorias golpistas\u201d.<\/p>\n<p>Os ministros Cristiano Zanin e C\u00e1rmen L\u00facia votaram com o relator para tornar r\u00e9us os sete oficiais da PMDF denunciados pela PGR. Falta o voto do ministro Luiz Fux.<\/p>\n<p>Se o entendimento do relator for mantido, os oficiais da PMDF v\u00e3o responder pelos crimes de aboli\u00e7\u00e3o violenta do Estado Democr\u00e1tico de Direito, golpe de Estado, dano qualificado pela viol\u00eancia, grave amea\u00e7a com emprego de substancia inflam\u00e1vel contra patrim\u00f4nio da Uni\u00e3o e com consider\u00e1vel preju\u00edzo para a v\u00edtima; deteriora\u00e7\u00e3o de patrim\u00f4nio tombado; e viola\u00e7\u00e3o de dever contratual de garante e por inger\u00eancia da norma.<\/p>\n<p>Metr\u00f3poles <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/stf-forma-maioria-para-tornar-reus-oficiais-que-chefiavam-pm-no-8-1-veja-quem-sao-os-denunciados\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>foto: metr\u00f3poles Dois ex-comandantes-gerais da PMDF e outros cinco policiais militares que atuaram durante as invas\u00f5es do 8 de janeiro foram acusados A Primeira Turma do Supremo Tribunal Federal (STF) formou maioria para aceitar a den\u00fancia da Procuradoria-Geral da Rep\u00fablica (PGR) e tornar r\u00e9us sete oficiais que integravam a c\u00fapula da Pol\u00edcia Militar do Distrito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[717,718,664,713,716,18,58,715,5,114,714,11],"class_list":["post-378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-chefiavam","tag-denunciados","tag-forma","tag-maioria","tag-oficiais","tag-para","tag-quem","tag-reus","tag-sao","tag-stf","tag-tornar","tag-veja"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=378"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/378\/revisions"}],"predecessor-version":[{"id":380,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/378\/revisions\/380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/379"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}