{"id":327,"date":"2024-02-13T22:35:54","date_gmt":"2024-02-13T22:35:54","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/13\/rei-charles-volta-ao-palacio-de-buckingham-apos-inicio-de-tratamento-contra-o-cancer\/"},"modified":"2024-02-14T02:46:21","modified_gmt":"2024-02-14T02:46:21","slug":"rei-charles-volta-ao-palacio-de-buckingham-apos-inicio-de-tratamento-contra-o-cancer","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/13\/rei-charles-volta-ao-palacio-de-buckingham-apos-inicio-de-tratamento-contra-o-cancer\/","title":{"rendered":"Rei Charles volta ao Pal\u00e1cio de Buckingham ap\u00f3s in\u00edcio de tratamento contra o c\u00e2ncer"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: Reuters via BBC<\/p>\n<h2 class=\"wp-block-heading\">Desde o an\u00fancio da doen\u00e7a, o rei estava na propriedade rural em Sandringham e chegou a adiar compromissos oficiais.<\/h2>\n<p>O\u00a0rei Charles III\u00a0voltou ao Pal\u00e1cio de Buckingham nesta ter\u00e7a-feira (13), de acordo com a rede brit\u00e2nica BBC. Ele havia passado uma semana fora de Londres ap\u00f3s o\u00a0an\u00fancio de que est\u00e1 em tratamento para combater um tipo de c\u00e2ncer.\u00a0<\/p>\n<p>O helic\u00f3ptero do rei foi visto chegando ao pal\u00e1cio nesta manh\u00e3. Esta \u00e9 a primeira vez que ele volta \u00e0 resid\u00eancia oficial depois de anunciar que adiaria alguns dos compromissos para o tratamento por recomenda\u00e7\u00e3o m\u00e9dica.\u00a0<\/p>\n<p>O rei estava em um das propriedade rurais da fam\u00edlia real, em Sandringham.<\/p>\n<h2 class=\"wp-block-heading\">Diagn\u00f3stico de c\u00e2ncer<\/h2>\n<p>Na \u00faltima semana, o pal\u00e1cio confirmou que o rei Charles III, de 75 anos, est\u00e1 com c\u00e2ncer.\u00a0<\/p>\n<p>Apesar disso, n\u00e3o informou qual o tipo de c\u00e2ncer est\u00e1 tratando. Recentemente, ele havia sido internado para tratar de um crescimento na pr\u00f3stata, mas que n\u00e3o era um tumor.\u00a0<\/p>\n<p>A divulga\u00e7\u00e3o de uma doen\u00e7a \u00e9 uma quebra de tradi\u00e7\u00e3o da fam\u00edlia real brit\u00e2nica. De acordo com a ag\u00eancia de not\u00edcias Associated Press, durante s\u00e9culos a realeza do pa\u00eds evitou falar sobre quest\u00f5es de sa\u00fade.\u00a0<\/p>\n<p>Segundo o pal\u00e1cio, o rei decidiu tornar o diagn\u00f3stico p\u00fablico para evitar especula\u00e7\u00f5es e para que isso melhore a compreens\u00e3o p\u00fablica do que \u00e9 ser afetado pelo c\u00e2ncer.\u00a0<\/p>\n<p>Na nota divulgada, o pal\u00e1cio ainda diz que o rei est\u00e1 \u201ctotalmente confiante\u201d em rela\u00e7\u00e3o ao tratamento e quer voltar \u00e0s suas fun\u00e7\u00f5es p\u00fablicas assim que poss\u00edvel.<\/p>\n<p>g1<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/rei-charles-volta-ao-palacio-de-buckingham-apos-inicio-de-tratamento-contra-o-cancer\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reuters via BBC Desde o an\u00fancio da doen\u00e7a, o rei estava na propriedade rural em Sandringham e chegou a adiar compromissos oficiais. O\u00a0rei Charles III\u00a0voltou ao Pal\u00e1cio de Buckingham nesta ter\u00e7a-feira (13), de acordo com a rede brit\u00e2nica BBC. Ele havia passado uma semana fora de Londres ap\u00f3s o\u00a0an\u00fancio de que est\u00e1 em tratamento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7,621,624,618,287,622,620,617,623,619],"class_list":["post-327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-apos","tag-buckingham","tag-cancer","tag-charles","tag-contra","tag-inicio","tag-palacio","tag-rei","tag-tratamento","tag-volta"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=327"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/327\/revisions"}],"predecessor-version":[{"id":329,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/327\/revisions\/329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/328"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}