{"id":1867,"date":"2024-03-12T18:06:45","date_gmt":"2024-03-12T18:06:45","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/12\/luciano-bivar-acusa-mulher-do-novo-presidente-do-uniao-brasil-de-roubar-cofre-veja-video\/"},"modified":"2024-03-12T18:24:15","modified_gmt":"2024-03-12T18:24:15","slug":"luciano-bivar-acusa-mulher-do-novo-presidente-do-uniao-brasil-de-roubar-cofre-veja-video","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/12\/luciano-bivar-acusa-mulher-do-novo-presidente-do-uniao-brasil-de-roubar-cofre-veja-video\/","title":{"rendered":"Luciano Bivar acusa mulher do novo presidente do Uni\u00e3o Brasil de roubar cofre; VEJA V\u00cdDEO"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>O deputado federal Luciano Bivar, ex-presidente do Uni\u00e3o Brasil, recentemente derrotado na corrida pela lideran\u00e7a do partido, alega que a esposa do novo l\u00edder da legenda, Ant\u00f4nio de Rueda, teria desviado \u201ctodo o dinheiro\u201d do cofre mantido em seu apartamento em Pernambuco.<\/p>\n<p>Ap\u00f3s participar de uma cerim\u00f4nia com o ex-presidente Lula no Pal\u00e1cio do Planalto, Bivar foi questionado sobre as alegadas amea\u00e7as feitas a Rueda durante a disputa pela lideran\u00e7a do Uni\u00e3o Brasil. Na segunda-feira (11\/3), duas resid\u00eancias da fam\u00edlia de Rueda foram alvo de inc\u00eandios em Pernambuco.<\/p>\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\">\n<p lang=\"pt\" dir=\"ltr\">Luciano Bivar acusa mulher do novo presidente do Uni\u00e3o Brasil de roubar cofre <a href=\"https:\/\/t.co\/dRS8Byh3ds\">pic.twitter.com\/dRS8Byh3ds<\/a><\/p>\n<p>\u2014 Diario do Brasil Not\u00edcias (@diariobrasil_n) <a href=\"https:\/\/twitter.com\/diariobrasil_n\/status\/1767613136687726605?ref_src=twsrc%5Etfw\">March 12, 2024<\/a><\/p><\/blockquote>\n<p>Luciano Bivar respondeu:<\/p>\n<p>\u201cS\u00e3o ila\u00e7\u00f5es. Por exemplo, a mulher do presidente foi no meu apartamento tamb\u00e9m e roubou meu cofre. Essas coisas tamb\u00e9m s\u00e3o acusa\u00e7\u00f5es. Eu cedi confiantemente o segredo e ela roubou todo o dinheiro\u201d, disse, referindo-se \u00e0 advogada e empres\u00e1ria Florinda Rueda.<\/p>\n<p>A equipe da coluna de Paulo Cappelli\/Metr\u00f3poles n\u00e3o logrou \u00eaxito em estabelecer contato com Rueda. O espa\u00e7o permanece dispon\u00edvel para qualquer manifesta\u00e7\u00e3o. Ap\u00f3s os incidentes de inc\u00eandio, o rec\u00e9m-eleito presidente do Uni\u00e3o Brasil procurou as autoridades policiais e denunciou supostas amea\u00e7as de morte provenientes de Bivar.<\/p>\n<p><strong><em>Com informa\u00e7\u00f5es de Metr\u00f3poles\/Paulo Cappelli<\/em><\/strong><\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/luciano-bivar-acusa-mulher-do-novo-presidente-do-uniao-brasil-de-roubar-cofre-veja-video\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado federal Luciano Bivar, ex-presidente do Uni\u00e3o Brasil, recentemente derrotado na corrida pela lideran\u00e7a do partido, alega que a esposa do novo l\u00edder da legenda, Ant\u00f4nio de Rueda, teria desviado \u201ctodo o dinheiro\u201d do cofre mantido em seu apartamento em Pernambuco. Ap\u00f3s participar de uma cerim\u00f4nia com o ex-presidente Lula no Pal\u00e1cio do Planalto, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2717,2716,94,2718,1147,324,79,377,910,955,11,197],"class_list":["post-1867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-acusa","tag-bivar","tag-brasil","tag-cofre","tag-luciano","tag-mulher","tag-novo","tag-presidente","tag-roubar","tag-uniao","tag-veja","tag-video"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1867"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1867\/revisions"}],"predecessor-version":[{"id":1869,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1867\/revisions\/1869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1868"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}