{"id":1864,"date":"2024-03-12T17:14:38","date_gmt":"2024-03-12T17:14:38","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/12\/descubra-os-segredos-da-ilha-que-esta-a-venda-por-r-10-milhoes-em-cidade-de-goias\/"},"modified":"2024-03-12T17:20:35","modified_gmt":"2024-03-12T17:20:35","slug":"descubra-os-segredos-da-ilha-que-esta-a-venda-por-r-10-milhoes-em-cidade-de-goias","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/12\/descubra-os-segredos-da-ilha-que-esta-a-venda-por-r-10-milhoes-em-cidade-de-goias\/","title":{"rendered":"Descubra os segredos da ilha que est\u00e1 \u00e0 venda por R$ 10 milh\u00f5es em cidade de Goi\u00e1s"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Est\u00e1 \u00e0 venda por R$ 10 milh\u00f5es uma ilha de 220 mil m\u00b2 em Itumbiara, sul de Goi\u00e1s, que conserva sua mata virgem. De acordo com o corretor de im\u00f3veis Welerson Antunes, \u00e9 poss\u00edvel desenvolver um condom\u00ednio horizontal ou at\u00e9 mesmo um resort nesse espa\u00e7o exclusivo cercado por \u00e1gua doce e privacidade.<\/p>\n<p>O an\u00fancio da ilha foi feito nas redes sociais do corretor, alcan\u00e7ando mais de 808 mil visualiza\u00e7\u00f5es at\u00e9 o momento. A propriedade despertou a curiosidade dos internautas, impressionados com a oportunidade apresentada.<\/p>\n<p>Localizada na divisa entre Goi\u00e1s e Minas Gerais, entre os munic\u00edpios de Itumbiara e Tupaciguara, a ilha tem origem em uma antiga fazenda, que foi desmembrada para a cria\u00e7\u00e3o de uma represa na regi\u00e3o.<\/p>\n<p>\u201cEssa ilha fica dentro da represa de Itumbiara. Aquilo tudo era uma fazenda. Quando foi desapropriado para fazer a represa, o propriet\u00e1rio da fazenda percebeu que ali iria se formar uma ilha, porque essa ilha era a parte mais alta da fazenda, ent\u00e3o o propriet\u00e1rio desmembrou esse terreno, onde hoje \u00e9 a ilha da fazenda\u201d, explicou Welerson.<\/p>\n<p>Em uma extens\u00e3o de 220 mil metros quadrados, aproximadamente 212,7 mil metros quadrados podem ser subdivididos em 194 lotes. Mesmo assim, restariam 26,8 mil metros quadrados destinados \u00e0 cria\u00e7\u00e3o de uma \u00e1rea de lazer, 1,9 mil metros quadrados para a constru\u00e7\u00e3o de um heliponto, 67,1 mil metros quadrados para a implementa\u00e7\u00e3o de ruas. Adicionalmente, seria poss\u00edvel preservar 56,7 mil metros quadrados de \u00e1rea verde.<\/p>\n<p>Em Goi\u00e1s, conforme informa\u00e7\u00f5es da Eletrobras, n\u00e3o h\u00e1 ilhas, mas sim remanescentes isolados em reservat\u00f3rios destinados \u00e0 gera\u00e7\u00e3o de energia el\u00e9trica, os quais est\u00e3o sob a concess\u00e3o da empresa. Esses remanescentes constituem propriedades privadas que podem ser de posse da concession\u00e1ria ou do propriet\u00e1rio do terreno cuja parcela foi afetada pela \u00e1rea de influ\u00eancia direta do empreendimento durante a fase de constru\u00e7\u00e3o.<\/p>\n<figure class=\"wp-block-image size-full\"><picture decoding=\"async\" class=\"wp-image-112455\"><source type=\"image\/webp\" srcset=\"https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/03\/image-152.png.webp 600w, https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/03\/image-152-300x188.png.webp 300w\" sizes=\"(max-width: 600px) 100vw, 600px\"\/><\/picture>\n<\/figure>\n<p class=\"has-small-font-size\">Propriedade pode dar espa\u00e7o \u00e0 resort ou condom\u00ednio horizontal em Itumbiara \u2014 Foto: Divulga\u00e7\u00e3o\/Welerson Antunes<\/p>\n<p><strong><em>Com informa\u00e7\u00f5es de G1<\/em><\/strong><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/descubra-os-segredos-da-ilha-que-esta-a-venda-por-r-10-milhoes-em-cidade-de-goias\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 \u00e0 venda por R$ 10 milh\u00f5es uma ilha de 220 mil m\u00b2 em Itumbiara, sul de Goi\u00e1s, que conserva sua mata virgem. De acordo com o corretor de im\u00f3veis Welerson Antunes, \u00e9 poss\u00edvel desenvolver um condom\u00ednio horizontal ou at\u00e9 mesmo um resort nesse espa\u00e7o exclusivo cercado por \u00e1gua doce e privacidade. O an\u00fancio da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[137,1795,509,2715,2118,365,192,2714,2399],"class_list":["post-1864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-cidade","tag-descubra","tag-esta","tag-goias","tag-ilha","tag-milhoes","tag-por","tag-segredos","tag-venda"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1864"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1864\/revisions"}],"predecessor-version":[{"id":1866,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1864\/revisions\/1866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1865"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}