{"id":1861,"date":"2024-03-12T16:15:17","date_gmt":"2024-03-12T16:15:17","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/12\/lula-e-um-exemplo-negativo-diz-brasileiro-eleito-em-portugal\/"},"modified":"2024-03-12T16:19:50","modified_gmt":"2024-03-12T16:19:50","slug":"lula-e-um-exemplo-negativo-diz-brasileiro-eleito-em-portugal","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/12\/lula-e-um-exemplo-negativo-diz-brasileiro-eleito-em-portugal\/","title":{"rendered":"Lula \u00e9 um exemplo negativo, diz brasileiro eleito em Portugal"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Reprodu\u00e7\u00e3o\/X marcussantosbtt \u2013 11.mar.2024<\/p>\n<h2 class=\"wp-block-heading\">Em entrevista ao \u201cO Globo\u201d, Marcus Santos, do Chega, afirmou que uma das bandeiras de seu partido \u00e9 o combate \u00e0 corrup\u00e7\u00e3o<\/h2>\n<p>O brasileiro Marcus Vin\u00edcius Teixeira dos Santos, eleito deputado em Portugal no domingo (10.mar.2024) pelo partido Chega, classificou o presidente Luiz In\u00e1cio Lula da Silva (PT) como um exemplo negativo para o combate \u00e0 corrup\u00e7\u00e3o.<\/p>\n<p>\u201cLula, para nosso partido e a direita, \u00e9 um exemplo do que n\u00e3o queremos em Portugal\u201d, afirmou o deputado. A declara\u00e7\u00e3o foi dada em entrevista ao jornal O Globo na 2\u00aa feira (11.mar).<\/p>\n<p>Em 7 de mar\u00e7o, o l\u00edder do partido Chega, Andr\u00e9 Ventura, afirmou que se fosse eleito como primeiro-ministro, proibiria a entrada de Lula no pa\u00eds em 25 de abril, data em que se comemora a Revolu\u00e7\u00e3o dos Cravos.<\/p>\n<p>\u201cSe o Chega vencer as elei\u00e7\u00f5es legislativas, a 25 de abril de 2024 o senhor presidente do Brasil, Lula da Silva, n\u00e3o vai entrar em Portugal\u201d, disse o deputado.<\/p>\n<p>O parlamentar disse ainda que pediria a pris\u00e3o de Lula se o chefe do Executivo brasileiro insistisse e fosse a Portugal. \u201cEu garanto-vos que, se eu for primeiro-ministro, o senhor Lula da Silva ficar\u00e1 no aeroporto. E, se insistir, vai para uma cadeia\u201d, declarou.<\/p>\n<p>Enquanto isso, o parlamentar disse que o ex-presidente Jair Bolsonaro (PL) est\u00e1 plenamente de acordo com as aspira\u00e7\u00f5es da direita portuguesa, e que a vertente est\u00e1 crescendo na Europa. Usou exemplos como Fran\u00e7a, Pol\u00f4nia, Hungria e Holanda.<\/p>\n<p>Assim como no pa\u00eds europeu, a direita tamb\u00e9m avan\u00e7ou na Argentina com a vit\u00f3ria do presidente Javier Milei, eleito em novembro de 2023. Nos Estados Unidos, Nikolas torce para que o ex-presidente Donald Trump ven\u00e7a a elei\u00e7\u00e3o para a Casa Branca neste ano.<\/p>\n<p>Quanto \u00e0 quest\u00e3o de imigrantes em Portugal, Santos declarou que o Chega defende o controle. \u201cN\u00e3o somos contra a imigra\u00e7\u00e3o, porque em Portugal a popula\u00e7\u00e3o \u00e9 muito envelhecida e precisamos de jovens para trabalhar. Defendemos que as pessoas venham para Portugal j\u00e1 com um contrato de trabalho. H\u00e1 muitos brasileiros que exploram brasileiros. As pessoas chegam aqui, muitas vezes sem casa e sem trabalho, e acabam caindo em redes de tr\u00e1fico humano\u201d, disse.<\/p>\n<p>Al\u00e9m disso, o deputado declarou que um dos principais objetivos de seu partido \u00e9 proteger os portugueses da criminalidade. Afirmou que, segundo a Pol\u00edcia Judici\u00e1ria portuguesa (Pol\u00edcia Federal do Brasil), h\u00e1 de 1.000 a 1.500 membros de uma fac\u00e7\u00e3o criminosa brasileira em Portugal. \u201cJ\u00e1 temos bandidos demais aqui\u201d, falou.<\/p>\n<p>O Chega, fundado em 2019, registrou um avan\u00e7o significativo na quantidade de cadeiras conquistadas nas elei\u00e7\u00f5es. A legenda conquistou 48 cadeiras das 230.<\/p>\n<p>Em 2019, havia conquistado somente uma cadeira, ocupado por Andr\u00e9 Ventura. J\u00e1 nas elei\u00e7\u00f5es antecipadas de 2022, a legenda passou para 12 deputados, se tornando a 3\u00aa maior for\u00e7a pol\u00edtica do pa\u00eds, posto que manteve no pleito deste ano.<\/p>\n<p>Poder 360<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/lula-e-um-exemplo-negativo-diz-brasileiro-eleito-em-portugal\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reprodu\u00e7\u00e3o\/X marcussantosbtt \u2013 11.mar.2024 Em entrevista ao \u201cO Globo\u201d, Marcus Santos, do Chega, afirmou que uma das bandeiras de seu partido \u00e9 o combate \u00e0 corrup\u00e7\u00e3o O brasileiro Marcus Vin\u00edcius Teixeira dos Santos, eleito deputado em Portugal no domingo (10.mar.2024) pelo partido Chega, classificou o presidente Luiz In\u00e1cio Lula da Silva (PT) como um exemplo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[254,243,2587,2712,242,2713,724],"class_list":["post-1861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-brasileiro","tag-diz","tag-eleito","tag-exemplo","tag-lula","tag-negativo","tag-portugal"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1861"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1861\/revisions"}],"predecessor-version":[{"id":1863,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1861\/revisions\/1863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1862"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}