{"id":1831,"date":"2024-03-11T22:59:55","date_gmt":"2024-03-11T22:59:55","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/11\/lula-mantem-jean-paul-prates-na-presidencia-da-petrobras-em-meio-a-turbulencias\/"},"modified":"2024-03-12T05:48:08","modified_gmt":"2024-03-12T05:48:08","slug":"lula-mantem-jean-paul-prates-na-presidencia-da-petrobras-em-meio-a-turbulencias","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/11\/lula-mantem-jean-paul-prates-na-presidencia-da-petrobras-em-meio-a-turbulencias\/","title":{"rendered":"Lula mant\u00e9m Jean Paul Prates na presid\u00eancia da Petrobras em meio a turbul\u00eancias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: Ricardo Stuckert \/ PR<\/p>\n<p>Ap\u00f3s uma reuni\u00e3o de mais de duas horas nesta segunda-feira (11) no Pal\u00e1cio do Planalto, o presidente Luiz In\u00e1cio Lula da Silva decidiu manter Jean Paul Prates na presid\u00eancia da Petrobras, em meio \u00e0 crise dos \u00faltimos dias. A informa\u00e7\u00e3o foi confirmada pelo jornal O Globo.<\/p>\n<p>Lula se reuniu com Prates, acompanhado dos ministros Fernando Haddad (Fazenda), Alexandre Silveira (Minas e Energia) e Rui Costa (Casa Civil), bem como diretores da Petrobras. O encontro ocorreu em um momento delicado para a empresa estatal, que enfrenta turbul\u00eancias devido \u00e0 decis\u00e3o de n\u00e3o distribuir dividendos extras aos acionistas.<\/p>\n<p>Questionado sobre sua perman\u00eancia no cargo, Prates respondeu confiante: \u201cClaro que sim, n\u00e3o teve problema nenhum com isso. Zero problema.\u201d<\/p>\n<p>Anteriormente, o presidente Lula havia se reunido por mais de tr\u00eas horas com o presidente da Petrobras e os ministros de Minas e Energia, Alexandre Silveira, e da Fazenda, Fernando Haddad, entre outros membros do governo, para discutir a decis\u00e3o da estatal.<\/p>\n<p>Este foi o primeiro encontro entre eles desde que a companhia anunciou a decis\u00e3o de n\u00e3o distribuir dividendos extraordin\u00e1rios aos investidores, o que resultou em uma queda significativa nas a\u00e7\u00f5es da empresa na semana passada.<\/p>\n<p>Em um comunicado divulgado na quinta-feira (7), a Petrobras informou que n\u00e3o pagaria dividendos extras e prop\u00f4s uma distribui\u00e7\u00e3o ordin\u00e1ria de R$ 14,2 bilh\u00f5es, destinando R$ 43,9 bilh\u00f5es para uma reserva estatut\u00e1ria.<\/p>\n<p>Apesar de registrar um lucro de cerca de R$ 31 bilh\u00f5es no quarto trimestre do ano passado, uma queda anual de 28%, os resultados da Petrobras foram ofuscados pelo conturbado cen\u00e1rio sobre a distribui\u00e7\u00e3o dos proventos.<\/p>\n<p>O Conselho de Administra\u00e7\u00e3o chegou a propor o pagamento de dividendos extraordin\u00e1rios, mas a proposta foi rejeitada ap\u00f3s vota\u00e7\u00e3o dos representantes do governo. A empresa justificou que a reserva ser\u00e1 utilizada para garantir bons proventos aos acionistas nos pr\u00f3ximos anos, diante dos investimentos previstos para os per\u00edodos de 2024 e 2025.<\/p>\n<p>Gazeta Brasil <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/lula-mantem-jean-paul-prates-na-presidencia-da-petrobras-em-meio-a-turbulencias\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Ricardo Stuckert \/ PR Ap\u00f3s uma reuni\u00e3o de mais de duas horas nesta segunda-feira (11) no Pal\u00e1cio do Planalto, o presidente Luiz In\u00e1cio Lula da Silva decidiu manter Jean Paul Prates na presid\u00eancia da Petrobras, em meio \u00e0 crise dos \u00faltimos dias. A informa\u00e7\u00e3o foi confirmada pelo jornal O Globo. Lula se reuniu com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2677,242,1776,2680,2678,1972,2679,2126,2681],"class_list":["post-1831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-jean","tag-lula","tag-mantem","tag-meio","tag-paul","tag-petrobras","tag-prates","tag-presidencia","tag-turbulencias"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1831"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1831\/revisions"}],"predecessor-version":[{"id":1833,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1831\/revisions\/1833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1832"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}