{"id":183,"date":"2024-02-03T15:15:44","date_gmt":"2024-02-03T15:15:44","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/03\/vacina-intranasal-apresenta-eficacia-de-100-contra-a-covid-19-em-testes-com-animais\/"},"modified":"2024-02-03T15:17:16","modified_gmt":"2024-02-03T15:17:16","slug":"vacina-intranasal-apresenta-eficacia-de-100-contra-a-covid-19-em-testes-com-animais","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/03\/vacina-intranasal-apresenta-eficacia-de-100-contra-a-covid-19-em-testes-com-animais\/","title":{"rendered":"Vacina intranasal apresenta efic\u00e1cia de 100% contra a COVID-19 em testes com animais"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Foto: Reprodu\u00e7\u00e3o.<\/p>\n<p>Uma vacina intranasal contra a COVID-19, desenvolvida no Brasil, demonstrou 100% de efic\u00e1cia em testes realizados em camundongos, conforme divulgado em um artigo na revista cient\u00edfica Vaccines.<\/p>\n<p>Proposta como uma alternativa \u00e0s vacinas atualmente dispon\u00edveis, que s\u00e3o administradas por via intramuscular, essa formula\u00e7\u00e3o estimula a imunidade atrav\u00e9s da mucosa do corpo, podendo ser aplicada pelo nariz ou pela boca na forma de spray. Este imunizante representa um dos primeiros do formato a ser testado globalmente.<\/p>\n<p>O professor Momtchilo Russo, do Departamento de Imunologia e um dos coordenadores do estudo, explicou que a escolha de uma vacina intranasal foi natural, considerando que o SARS-CoV-2 \u00e9 um v\u00edrus respirat\u00f3rio. A vacina age neutralizando o v\u00edrus nas vias a\u00e9reas superiores, onde ele tenta entrar no corpo humano. Nas mucosas, ocorre uma produ\u00e7\u00e3o significativa de anticorpos, incluindo a imunoglobulina A (IgA), uma prote\u00edna fundamental para a imunidade.<\/p>\n<p>A formula\u00e7\u00e3o utiliza a prote\u00edna Spike (S) como ant\u00edgeno, semelhante a outras vacinas j\u00e1 em uso. Quando uma pessoa \u00e9 infectada, o sistema imunol\u00f3gico detecta essa prote\u00edna S, presente no SARS-CoV-2, induzindo a produ\u00e7\u00e3o de anticorpos IgA e iniciando a resposta contra o v\u00edrus no local.<\/p>\n<p>Al\u00e9m disso, a vacina cont\u00e9m um adjuvante j\u00e1 aprovado para uso humano, chamado CpG, que potencializa sua efic\u00e1cia. O CpG, composto por oligonucleot\u00eddeos de citosina e guanina, \u00e9 combinado com a prote\u00edna S e inserido em uma part\u00edcula de lip\u00eddio chamada lipossoma.<\/p>\n<p>Segundo Russo, essa t\u00e9cnica \u00e9 mais f\u00e1cil de ser realizada em compara\u00e7\u00e3o com as vacinas que usam RNA mensageiro ou adenov\u00edrus, sendo mais simples de produzir e armazenar. Outra vantagem \u00e9 a efic\u00e1cia no pulm\u00e3o, j\u00e1 que o imunizante atinge mais rapidamente o \u00f3rg\u00e3o ao circular pela mucosa.<\/p>\n<p>Nos testes com camundongos transg\u00eanicos, que expressam o receptor do v\u00edrus SARS-CoV-2, todos os animais vacinados foram protegidos contra a infec\u00e7\u00e3o, considerando mortalidade ou perda de peso. A vacina intranasal mostrou-se mais eficiente na elimina\u00e7\u00e3o do v\u00edrus no pulm\u00e3o e na indu\u00e7\u00e3o da produ\u00e7\u00e3o de anticorpos IgA, em compara\u00e7\u00e3o com a aplica\u00e7\u00e3o subcut\u00e2nea do mesmo imunizante.<\/p>\n<p>Os resultados indicam uma redu\u00e7\u00e3o na carga viral no pulm\u00e3o, sugerindo que a transmiss\u00e3o do v\u00edrus pode ser menor com a vacina intranasal. Al\u00e9m disso, foi observada prote\u00e7\u00e3o contra diversas variantes do SARS-CoV-2, incluindo as variantes Gamma, Delta e \u00d4micron.<\/p>\n<p>Russo destaca o esfor\u00e7o para tornar a vacina totalmente nacional, com todos os insumos, instala\u00e7\u00f5es e expertise dispon\u00edveis no pa\u00eds. Agora, o imunizante avan\u00e7ar\u00e1 para outras etapas de teste ap\u00f3s o apoio da Fapesp e a colabora\u00e7\u00e3o entre o Instituto de Ci\u00eancias Biom\u00e9dicas da Universidade de S\u00e3o Paulo (ICB-USP), a Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz), a Faculdade de Ci\u00eancias Farmac\u00eauticas (FCF-USP), o Instituto de Medicina Tropical (IMT-USP) e a Universidade Federal do Rio de Janeiro (UFRJ).<\/p>\n<p>Com informa\u00e7\u00f5es do Poder 360.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/vacina-intranasal-apresenta-eficacia-de-100-contra-a-covid-19-em-testes-com-animais\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reprodu\u00e7\u00e3o. Uma vacina intranasal contra a COVID-19, desenvolvida no Brasil, demonstrou 100% de efic\u00e1cia em testes realizados em camundongos, conforme divulgado em um artigo na revista cient\u00edfica Vaccines. Proposta como uma alternativa \u00e0s vacinas atualmente dispon\u00edveis, que s\u00e3o administradas por via intramuscular, essa formula\u00e7\u00e3o estimula a imunidade atrav\u00e9s da mucosa do corpo, podendo ser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[290,285,287,288,286,284,289,283],"class_list":["post-183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-animais","tag-apresenta","tag-contra","tag-covid19","tag-eficacia","tag-intranasal","tag-testes","tag-vacina"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=183"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/183\/revisions"}],"predecessor-version":[{"id":185,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/183\/revisions\/185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/184"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}