{"id":1828,"date":"2024-03-11T23:13:08","date_gmt":"2024-03-11T23:13:08","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/11\/carolina-de-toni-pauta-tres-projetos-que-elevam-penas-de-crimes-em-primeira-reuniao-da-ccj\/"},"modified":"2024-03-12T04:46:04","modified_gmt":"2024-03-12T04:46:04","slug":"carolina-de-toni-pauta-tres-projetos-que-elevam-penas-de-crimes-em-primeira-reuniao-da-ccj","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/11\/carolina-de-toni-pauta-tres-projetos-que-elevam-penas-de-crimes-em-primeira-reuniao-da-ccj\/","title":{"rendered":"Carolina de Toni pauta tr\u00eas projetos que elevam penas de crimes em primeira reuni\u00e3o da CCJ"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><em>Foto:\u00a0Divulga\u00e7\u00e3o\/C\u00e2mara dos Deputados.<\/em><\/p>\n<p>Bolsonarista, a nova presidente da comiss\u00e3o mais importante da Casa colocou na pauta desta ter\u00e7a-feira, 12, projetos de nomes visados da oposi\u00e7\u00e3o, como Kim Kataguiri e Carla Zambelli<\/p>\n<p>Em sua estreia presidindo a Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) da C\u00e2mara dos Deputados, Caroline de Toni (PL-SC) pautou tr\u00eas projetos que aumentam penas de crimes. As propostas ser\u00e3o analisadas pela comiss\u00e3o, que se re\u00fane pela primeira vez para deliberar neste ano nesta ter\u00e7a-feira, 12.<\/p>\n<p>A lista de projetos foi definida na \u00faltima sexta-feira, 8. As propostas s\u00e3o de autoria dos deputados Kim Kataguiri (Uni\u00e3o-SP), Carla Zambelli (PL-SP) e Gildenemir de Lima Sousa, conhecido como Pastor Gil (PL-MA). Todas, ao proporem altera\u00e7\u00f5es no C\u00f3digo Penal, endurecem penas de crimes j\u00e1 previstos na lei, como estelionato e tr\u00e1fico de drogas, e precisam de vota\u00e7\u00e3o no Plen\u00e1rio da Casa para serem aprovadas. (Leia abaixo o que diz cada projeto)<\/p>\n<p>Bolsonarista do partido do ex-presidente Jair Bolsonaro, Caroline foi escolhida nesta quarta-feira, 6, indicada pelo PL para a lideran\u00e7a do colegiado justamente para conduzir para vota\u00e7\u00e3o o maior n\u00famero poss\u00edvel de pautas conservadoras e deix\u00e1-las prontas para o plen\u00e1rio da Casa. Em entrevista \u00e0 Coluna do Estad\u00e3o, a deputada disse que s\u00f3 vai pautar mat\u00e9rias de costumes se houver garantia de vit\u00f3ria. \u201cN\u00e3o adianta sair pautando temas de costumes, como poderia ser a vontade de um deputado oposicionista, e chegar l\u00e1 na frente e n\u00e3o temos os votos. Temos que ponderar o momento social e pol\u00edtico\u201d, disse a deputada.<\/p>\n<p>Entre os textos que devem avan\u00e7ar com o comando da parlamentar, est\u00e3o a proposta de emenda \u00e0 Constitui\u00e7\u00e3o (PEC) que limita as decis\u00f5es monocr\u00e1ticas dos ministros do Supremo Tribunal Federal (STF) e o projeto de lei que pro\u00edbe o casamento homoafetivo. Veja abaixo os projetos de lei pautados para a pr\u00f3xima reuni\u00e3o da CCJ que visam aumentar penas:<\/p>\n<h3 class=\"wp-block-heading\">PL 986\/2019<\/h3>\n<p>De autoria do deputado Kim Kataguiri (Uni\u00e3o-SP), o projeto determina a pena m\u00ednima de 25 anos para quem praticar crimes graves por mais de duas vezes. \u201cO intuito \u00e9 que o reincidente passe a cumprir pena mais pesada a partir do momento que praticar pela terceira vez algum dos crimes que a proposta menciona, a fim de evitar que o agente pratique v\u00e1rias vezes crimes de maior gravidade\u201d, alega o deputado na justificativa do projeto.<\/p>\n<p>Os crimes aos quais a regra proposta se aplicaria s\u00e3o os dolosos contra a vida, hediondos e de tr\u00e1fico de drogas. Kataguiri se baseia na legisla\u00e7\u00e3o americana, medida que l\u00e1, segundo o autor, \u00e9 denominada<em>three strikes law<\/em>\u00a0(tr\u00eas crimes e fora, em tradu\u00e7\u00e3o livre).<\/p>\n<h3 class=\"wp-block-heading\">PL 464\/2022<\/h3>\n<p>Proposto no dia internacional de luta das mulheres de 2022 por Carla Zambelli (PL-SP), o projeto de lei visa ampliar as circunst\u00e2ncias agravantes do crime de estelionato em que haja explora\u00e7\u00e3o sexual ou a v\u00edtima seja refugiada.<\/p>\n<p>O projeto prev\u00ea o dobro de pena, que atualmente \u00e9 de um a cinco anos e multa, se o estelionato for cometido para fins de explora\u00e7\u00e3o sexual, viol\u00eancia contra mulher, crian\u00e7a ou adolescente ou tr\u00e1fico de pessoas. A pena para o crime aumenta de 1\/3 ao dobro se for contra idoso ou vulner\u00e1vel. O projeto inclui na lista refugiados, asilados pol\u00edticos e pessoas em local afetado por guerra e calamidades p\u00fablicas \u00e0 lista de vulner\u00e1veis.<\/p>\n<h3 class=\"wp-block-heading\">PL 2663\/2023<\/h3>\n<p>Em mais uma mat\u00e9ria para alterar o crime de estelionato no C\u00f3digo Penal, o deputado Pastor Gil (PL-MA) prop\u00f4s aumentar a pena do crime quando for cometido contra crian\u00e7a, adolescente, idoso, pessoa com defici\u00eancia ou com baixo n\u00edvel de escolaridade.<\/p>\n<p>Segundo a justificativa, a atual legisla\u00e7\u00e3o deixa margem para o juiz aplicar a pena conforme o resultado do crime, o que, para o autor da proposta, pode fazer com que o criminoso \u201cn\u00e3o receba uma puni\u00e7\u00e3o proporcional \u00e0 repugn\u00e2ncia da conduta\u201d.<\/p>\n<p>\u201cNosso prop\u00f3sito \u00e9 a aplica\u00e7\u00e3o de uma puni\u00e7\u00e3o mais severa e sem qualquer car\u00e1ter de subjetividade ao agente que se aproveita da vulnerabilidade dessas v\u00edtimas para causar-lhes preju\u00edzo financeiro, moral e emocional, desestimulando, assim, a pr\u00e1tica de tal conduta.\u201d<\/p>\n<h3 class=\"wp-block-heading\">Outras pautas<\/h3>\n<p>H\u00e1 ainda outros projetos na pauta de vota\u00e7\u00e3o. Entre eles um que transforma o per\u00edmetro de complexos prisionais em \u00e1reas de Seguran\u00e7a. De autoria dos deputados Capit\u00e3o Alberto Neto (Republicanos-AM) e Gurgel (PSL-RJ) e aprovada em outras duas comiss\u00f5es, o projeto quer que uma faixa de 250 metros a partir do limite dos complexos penitenci\u00e1rios e unidades prisionais tenha maior controle do Estado, como restri\u00e7\u00e3o do sobrevoo de aeronaves, controle de residentes, de ocupa\u00e7\u00e3o do solo e de telefones celulares, entre outras medidas.<\/p>\n<p>Estad\u00e3o<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/carolina-de-toni-pauta-tres-projetos-que-elevam-penas-de-crimes-em-primeira-reuniao-da-ccj\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto:\u00a0Divulga\u00e7\u00e3o\/C\u00e2mara dos Deputados. Bolsonarista, a nova presidente da comiss\u00e3o mais importante da Casa colocou na pauta desta ter\u00e7a-feira, 12, projetos de nomes visados da oposi\u00e7\u00e3o, como Kim Kataguiri e Carla Zambelli Em sua estreia presidindo a Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) da C\u00e2mara dos Deputados, Caroline de Toni (PL-SC) pautou tr\u00eas projetos que aumentam [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[105,2676,1684,2674,2673,2675,221,2529,2538,2551,1207],"class_list":["post-1828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-carolina","tag-ccj","tag-crimes","tag-elevam","tag-pauta","tag-penas","tag-primeira","tag-projetos","tag-reuniao","tag-toni","tag-tres"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1828"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1828\/revisions"}],"predecessor-version":[{"id":1830,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1828\/revisions\/1830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1829"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}