{"id":1819,"date":"2024-03-11T23:27:03","date_gmt":"2024-03-11T23:27:03","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/11\/de-novo-petrobras-visita-venezuela-para-avaliar-possiveis-negocios\/"},"modified":"2024-03-12T00:57:07","modified_gmt":"2024-03-12T00:57:07","slug":"de-novo-petrobras-visita-venezuela-para-avaliar-possiveis-negocios","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/11\/de-novo-petrobras-visita-venezuela-para-avaliar-possiveis-negocios\/","title":{"rendered":"De novo: Petrobras visita Venezuela para avaliar poss\u00edveis neg\u00f3cios"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>The Photographer\/Wikimedia Commons<\/p>\n<h2 class=\"wp-block-heading\">Executivos e t\u00e9cnicos da estatal foram a unidades de produ\u00e7\u00e3o e refino da PDVSA na regi\u00e3o de Maracaibo; nenhum acordo foi fechado<\/h2>\n<p>Uma comitiva da\u00a0Petrobras\u00a0realizou uma visita na Venezuela na \u00faltima semana para avaliar poss\u00edveis oportunidades de neg\u00f3cios no pa\u00eds. A viagem foi realizada a convite do governo de Nicol\u00e1s Maduro, que tem recebido outras petroleiras estrangeiras, apesar das amea\u00e7as de san\u00e7\u00f5es dos Estados Unidos em fun\u00e7\u00e3o do processo eleitoral deste ano.<\/p>\n<p>Executivos e t\u00e9cnicos da estatal brasileira visitaram unidades de produ\u00e7\u00e3o de \u00f3leo e g\u00e1s e de refino na regi\u00e3o de Maracaibo, importante prov\u00edncia petrol\u00edfera no pa\u00eds. Esses ativos s\u00e3o operados pela\u00a0PDVSA(Petr\u00f3leos de Venezuela), que pertence ao governo venezuelano.<\/p>\n<p>A Petrobras tem retomado os planos de investir no exterior. O presidente\u00a0Luiz In\u00e1cio Lula da Silva\u00a0(PT) defende essa expans\u00e3o. Desde 2023, a estatal j\u00e1 assinou memorandos de entendimento para avaliar parcerias com petroleiras em v\u00e1rios pa\u00edses, como no Oriente M\u00e9dio, na China e na \u00c1frica.\u00a0<\/p>\n<p>No caso da Venezuela, no entanto, nenhum acordo foi fechado na visita. Apesar de a companhia enxergar espa\u00e7o para parcerias, pesa a incerteza sobre quanto tempo durar\u00e1 o abrandamento das san\u00e7\u00f5es impostas ao pa\u00eds pelo governo Joe Biden.\u00a0<\/p>\n<p>Maduro vislumbra um futuro com menos san\u00e7\u00f5es e, com isso, almeja ressuscitar a produ\u00e7\u00e3o e a ind\u00fastria de petr\u00f3leo do pa\u00eds. As restri\u00e7\u00f5es internacionais e seus impactos na economia local resultaram em anos de baixos investimentos no setor.<\/p>\n<p>O\u00a0<strong>Poder360<\/strong>\u00a0procurou a Petrobras para perguntar se gostaria de se manifestar a respeito das visitas. Por meio de sua assessoria, a estatal informou que n\u00e3o ir\u00e1 se pronunciar.<\/p>\n<p>Poder 360<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/de-novo-petrobras-visita-venezuela-para-avaliar-possiveis-negocios\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Photographer\/Wikimedia Commons Executivos e t\u00e9cnicos da estatal foram a unidades de produ\u00e7\u00e3o e refino da PDVSA na regi\u00e3o de Maracaibo; nenhum acordo foi fechado Uma comitiva da\u00a0Petrobras\u00a0realizou uma visita na Venezuela na \u00faltima semana para avaliar poss\u00edveis oportunidades de neg\u00f3cios no pa\u00eds. A viagem foi realizada a convite do governo de Nicol\u00e1s Maduro, que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2668,2670,79,18,1972,2669,1343,2667],"class_list":["post-1819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-avaliar","tag-negocios","tag-novo","tag-para","tag-petrobras","tag-possiveis","tag-venezuela","tag-visita"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1819"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1819\/revisions"}],"predecessor-version":[{"id":1821,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1819\/revisions\/1821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1820"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}