{"id":1685,"date":"2024-03-09T21:06:28","date_gmt":"2024-03-09T21:06:28","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/09\/presidente-do-chile-reitera-criticas-a-maduro-apos-lula-expressar-confianca-em-eleicoes-na-venezuela\/"},"modified":"2024-03-09T21:11:48","modified_gmt":"2024-03-09T21:11:48","slug":"presidente-do-chile-reitera-criticas-a-maduro-apos-lula-expressar-confianca-em-eleicoes-na-venezuela","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/09\/presidente-do-chile-reitera-criticas-a-maduro-apos-lula-expressar-confianca-em-eleicoes-na-venezuela\/","title":{"rendered":"Presidente do Chile reitera cr\u00edticas a Maduro ap\u00f3s Lula expressar confian\u00e7a em elei\u00e7\u00f5es na Venezuela"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Ap\u00f3s o presidente brasileiro, Luiz In\u00e1cio Lula da Silva, expressar confian\u00e7a nas elei\u00e7\u00f5es presidenciais venezuelanas e sugerir que a oposi\u00e7\u00e3o deveria evitar \u201cchorar\u201d, o presidente do Chile, Gabriel Boric, reafirmou suas den\u00fancias sobre viola\u00e7\u00f5es de direitos humanos e pol\u00edticos na Venezuela. Boric destacou a repress\u00e3o a opositores do governo de Nicol\u00e1s Maduro, enquanto Lula evita mencionar esses aspectos.<\/p>\n<p>O l\u00edder chileno enfatizou a coer\u00eancia da posi\u00e7\u00e3o do Estado chileno, que denuncia viola\u00e7\u00f5es de direitos humanos em diversos contextos, incluindo Venezuela, Ucr\u00e2nia e Gaza. Boric comentou o assassinato do ex-militar venezuelano Ronald Ojeda em Santiago e reiterou a condena\u00e7\u00e3o \u00e0s viola\u00e7\u00f5es de direitos humanos pelo regime de Maduro.<\/p>\n<p>As declara\u00e7\u00f5es de Lula foram alvo de cr\u00edticas de Mar\u00eda Corina Machado, principal opositora de Maduro e impedida de concorrer nas elei\u00e7\u00f5es. Ela rejeitou a sugest\u00e3o de Lula de que a oposi\u00e7\u00e3o venezuelana n\u00e3o deveria \u201cchorar\u201d e afirmou que luta pelos direitos dos venezuelanos.<\/p>\n<p>Boric destacou a gravidade do caso de Ojeda e reafirmou o compromisso do governo chileno com a defesa da democracia na Venezuela. Enquanto Lula busca evitar pol\u00eamicas em rela\u00e7\u00e3o ao governo de Maduro, o presidente chileno mant\u00e9m uma postura cr\u00edtica em rela\u00e7\u00e3o \u00e0s viola\u00e7\u00f5es de direitos no pa\u00eds vizinho.<\/p>\n<p>Com informa\u00e7\u00f5es do jornal O Globo.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/presidente-do-chile-reitera-criticas-a-maduro-apos-lula-expressar-confianca-em-eleicoes-na-venezuela\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s o presidente brasileiro, Luiz In\u00e1cio Lula da Silva, expressar confian\u00e7a nas elei\u00e7\u00f5es presidenciais venezuelanas e sugerir que a oposi\u00e7\u00e3o deveria evitar \u201cchorar\u201d, o presidente do Chile, Gabriel Boric, reafirmou suas den\u00fancias sobre viola\u00e7\u00f5es de direitos humanos e pol\u00edticos na Venezuela. Boric destacou a repress\u00e3o a opositores do governo de Nicol\u00e1s Maduro, enquanto Lula evita [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7,2512,2515,1632,992,2514,242,2255,377,2513,1343],"class_list":["post-1685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-apos","tag-chile","tag-confianca","tag-criticas","tag-eleicoes","tag-expressar","tag-lula","tag-maduro","tag-presidente","tag-reitera","tag-venezuela"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1685"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1685\/revisions"}],"predecessor-version":[{"id":1687,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1685\/revisions\/1687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1686"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}