{"id":1594,"date":"2024-03-07T22:56:38","date_gmt":"2024-03-07T22:56:38","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/07\/o-condominio-pode-ter-grupo-no-whatsapp-saiba-como-utilizar-essa-ferramenta-de-forma-adequada-e-respeitando-a-lgpd\/"},"modified":"2024-03-08T08:17:58","modified_gmt":"2024-03-08T08:17:58","slug":"o-condominio-pode-ter-grupo-no-whatsapp-saiba-como-utilizar-essa-ferramenta-de-forma-adequada-e-respeitando-a-lgpd","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/07\/o-condominio-pode-ter-grupo-no-whatsapp-saiba-como-utilizar-essa-ferramenta-de-forma-adequada-e-respeitando-a-lgpd\/","title":{"rendered":"O condom\u00ednio pode ter grupo no WhatsApp? Saiba como utilizar essa ferramenta de forma adequada e respeitando a LGPD"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>foto: TechTudo<\/p>\n<p>O uso de grupos de WhatsApp em condom\u00ednios \u00e9 cada vez mais comum. Essa ferramenta pode ser uma \u00f3tima aliada do s\u00edndico, pois permite centralizar e facilitar a comunica\u00e7\u00e3o entre o(a) S\u00edndico(a) e os cond\u00f4minos.<\/p>\n<p>No entanto, \u00e9 importante ter bom senso para n\u00e3o extrapolar os limites permitidos legalmente. Al\u00e9m disso, \u00e9 fundamental respeitar a privacidade e a integridade dos cond\u00f4minos, evitando a exposi\u00e7\u00e3o desnecess\u00e1ria de informa\u00e7\u00f5es pessoais.<\/p>\n<p><strong>1) O que \u00e9 permitido?<\/strong><\/p>\n<ul>\n<li>Comunicados simples de gest\u00e3o: avisos sobre reuni\u00f5es, eventos e presta\u00e7\u00e3o de contas.\u00a0<\/li>\n<li>Exposi\u00e7\u00e3o de problemas e solu\u00e7\u00f5es de interesse da coletividade condominial: necessidade de uma obra e problemas com equipamentos.<\/li>\n<li>Comunicados diversos de interesse geral: informa\u00e7\u00f5es sobre seguran\u00e7a e dicas de conviv\u00eancia.<\/li>\n<\/ul>\n<p>Essas informa\u00e7\u00f5es compartilhadas no grupo de WhatsApp auxiliam no fortalecimento da comunidade condominial, proporcionando aos moradores um senso de pertencimento e mantendo-os atualizados sobre quest\u00f5es relevantes.\u00a0<\/p>\n<p><strong>2) O que n\u00e3o \u00e9 permitido?<\/strong><\/p>\n<ul>\n<li>Exposi\u00e7\u00e3o de inadimplentes.<\/li>\n<li>Exposi\u00e7\u00e3o de situa\u00e7\u00f5es particulares de cond\u00f4minos: \u00c9 uma viola\u00e7\u00e3o de privacidade.<\/li>\n<li>Utiliza\u00e7\u00e3o do grupo para ofender as outras pessoas.<\/li>\n<li>Cobran\u00e7as: o grupo de WhatsApp n\u00e3o deve ser usado para fazer cobran\u00e7as.<\/li>\n<li>Exposi\u00e7\u00e3o de dados pessoais de cond\u00f4minos: Preserve a privacidade dos moradores, visitantes e tamb\u00e9m dos funcion\u00e1rios. O atestado m\u00e9dico de um funcion\u00e1rio n\u00e3o deve ser enviado no Grupo para justificar a falta.<\/li>\n<\/ul>\n<p>Ao seguir essas orienta\u00e7\u00f5es, voc\u00ea poder\u00e1 usar o grupo de WhatsApp do condom\u00ednio de forma adequada, garantindo a comunica\u00e7\u00e3o eficiente e o respeito entre todos os cond\u00f4minos.<\/p>\n<p><strong>Dica:<\/strong>\u00a0Uma maneira eficiente de assegurar o bom uso do grupo \u00e9 estabelecer regras claras e compartilh\u00e1-las com todos os cond\u00f4minos. Isso ajudar\u00e1 a evitar conflitos e a garantir o bom uso da ferramenta.<\/p>\n<p>Quem deve enviar mensagens no grupo do condom\u00ednio? Sugiro que apenas os administradores (s\u00edndico e subs\u00edndico) estejam habilitados para o envio de mensagens. Assim, \u00e9 mantida a finalidade do grupo. Essa postura protege o condom\u00ednio de processos judiciais.<\/p>\n<p>\u00c9 importante destacar que, ao adotar essas pr\u00e1ticas, o condom\u00ednio demonstra preocupa\u00e7\u00e3o com a privacidade dos cond\u00f4minos, o bom conv\u00edvio coletivo e a transpar\u00eancia na gest\u00e3o. E quando se trata do uso do WhatsApp, o S\u00edndico desempenha um papel fundamental na gest\u00e3o dessa ferramenta t\u00e3o presente em nosso cotidiano.<\/p>\n<p>Ao seguir as diretrizes e recomenda\u00e7\u00f5es apresentadas, voc\u00ea estar\u00e1 no caminho para um uso consciente e respons\u00e1vel do WhatsApp em seu condom\u00ednio. N\u00e3o deixe de explorar todas as vantagens que essa ferramenta pode oferecer, mantendo sempre o respeito, a privacidade e a transpar\u00eancia como pilares fundamentais da sua utiliza\u00e7\u00e3o.<\/p>\n<p>Portal Migalhas <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/o-condominio-pode-ter-grupo-no-whatsapp-saiba-como-utilizar-essa-ferramenta-de-forma-adequada-e-respeitando-a-lgpd\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>foto: TechTudo O uso de grupos de WhatsApp em condom\u00ednios \u00e9 cada vez mais comum. Essa ferramenta pode ser uma \u00f3tima aliada do s\u00edndico, pois permite centralizar e facilitar a comunica\u00e7\u00e3o entre o(a) S\u00edndico(a) e os cond\u00f4minos. No entanto, \u00e9 importante ter bom senso para n\u00e3o extrapolar os limites permitidos legalmente. Al\u00e9m disso, \u00e9 fundamental [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2390,61,2389,1849,2157,664,1262,2392,549,2391,63,401,2338,480],"class_list":["post-1594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-adequada","tag-como","tag-condominio","tag-essa","tag-ferramenta","tag-forma","tag-grupo","tag-lgpd","tag-pode","tag-respeitando","tag-saiba","tag-ter","tag-utilizar","tag-whatsapp"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1594"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1594\/revisions"}],"predecessor-version":[{"id":1596,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1594\/revisions\/1596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1595"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}