{"id":1570,"date":"2024-03-07T22:33:18","date_gmt":"2024-03-07T22:33:18","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/07\/atriz-da-globo-se-atrapalha-e-solta-palavrao-ao-vivo-veja-video\/"},"modified":"2024-03-07T22:52:43","modified_gmt":"2024-03-07T22:52:43","slug":"atriz-da-globo-se-atrapalha-e-solta-palavrao-ao-vivo-veja-video","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/07\/atriz-da-globo-se-atrapalha-e-solta-palavrao-ao-vivo-veja-video\/","title":{"rendered":"Atriz da Globo se atrapalha e solta palavr\u00e3o ao vivo; VEJA V\u00cdDEO"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>REPRODU\u00c7\u00c3O\/TV GLOBO<\/p>\n<p>Elogiada por sua atua\u00e7\u00e3o como a In\u00e1cia de Renascer, Edvana Carvalho se atrapalhou durante uma participa\u00e7\u00e3o no Encontro com Patr\u00edcia Poeta desta quinta-feira (7) e acabou soltando um palavr\u00e3o ao vivo na Globo. Em vez de falar \u201cfog\u00e3o\u201d, a atriz falou que sua personagem usa o \u201cc*z\u00e3o\u201d de Jos\u00e9 Inoc\u00eancio (Marcos Palmeira) para cozinhar. Ela se corrigiu rapidamente.<\/p>\n<p>A gafe ocorreu durante uma visita de Tati Machado \u00e0 cozinha cenogr\u00e1fica que In\u00e1cia utiliza em cenas da novela das nove da Globo. A rep\u00f3rter pediu para que a atriz fizesse um tour pelo cen\u00e1rio, para mostrar curiosidades da produ\u00e7\u00e3o.<\/p>\n<p>\u201cA cozinha \u00e9 o santu\u00e1rio da In\u00e1cia. Acho que Jos\u00e9 Inoc\u00eancio manda da sala para fora, na fazenda inteira, menos na cozinha. Cozinha \u00e9 um lugar de afeto, de aconchego, onde a gente se re\u00fane, se alimenta\u201d, discursou Edvana.<\/p>\n<p>\u201cEnt\u00e3o, aqui na cozinha de In\u00e1cia tem sempre um pezinho de arruda, pra espantar mau olhado. Ela tem essas folhinhas que s\u00e3o comest\u00edveis, enquanto eu t\u00f4 fazendo uma cena ou outra, preparando uma comida, eu uso. Folha de louro, tem de tudo\u201d, continuou a atriz.<\/p>\n<p>Edvana surpreendeu Patr\u00edcia ao revelar que alguns dos alimentos espalhados pela cozinha s\u00e3o de mentira. \u201cOs ovos s\u00e3o cenogr\u00e1ficos, mas daqui a pouco chegam os de verdade. Aqui vai ficar cheio de hortifruti, tudo florido. E \u00e9 de verdade, Jos\u00e9 Inoc\u00eancio \u00e9 agrofloresta\u201d, discursou.<\/p>\n<p>\u201cE tem compostagem tamb\u00e9m! Na cozinha da In\u00e1cia a gente faz compostagem\u2026 Os legumes, as verduras, as frutas, a gente p\u00f5e aqui as cascas para depois reutilizar.\u201d<\/p>\n<p>\u201cTemos o fog\u00e3o a lenha, que a gente usa para uma comida mais primorosa. Mas, no dia a dia, In\u00e1cia usa o c*z\u00e3o\u2026 O fog\u00e3o a g\u00e1s mesmo\u201d, se corrigiu a veterana, que rapidamente mudou o tema. \u201cT\u00e1 sendo uma experi\u00eancia maravilhosa.\u201d<\/p>\n<p>A atriz e poetisa ainda falou sobre a import\u00e2ncia de viver uma personagem baiana no hor\u00e1rio mais nobre da televis\u00e3o brasileira. \u201cPra mim \u00e9 uma honra poder representar minhas tias, a minha m\u00e3e, as minhas av\u00f3s\u201d, valorizou a artista, que nasceu em Salvador.<\/p>\n<p>\u201cE saber que tem muitas mulheres no Brasil que se identificam com a In\u00e1cia, que \u00e9 uma guerreira, uma mulher de pura sabedoria e com um cora\u00e7\u00e3o t\u00e3o maternal, t\u00e3o grande \u00e9 esse amor que ela tem por todos que passam aqui pela cozinha dela.\u201d<\/p>\n<p>Confira a gafe de Edvana Carvalho no Encontro:<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><noscript><iframe title=\"In\u00e1cia de Renascer, Edvana Carvalho se atrapalha e solta palavr\u00e3o ao vivo na Globo\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/GVbbBxn_scY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/noscript><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/atriz-da-globo-se-atrapalha-e-solta-palavrao-ao-vivo-veja-video\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REPRODU\u00c7\u00c3O\/TV GLOBO Elogiada por sua atua\u00e7\u00e3o como a In\u00e1cia de Renascer, Edvana Carvalho se atrapalhou durante uma participa\u00e7\u00e3o no Encontro com Patr\u00edcia Poeta desta quinta-feira (7) e acabou soltando um palavr\u00e3o ao vivo na Globo. Em vez de falar \u201cfog\u00e3o\u201d, a atriz falou que sua personagem usa o \u201cc*z\u00e3o\u201d de Jos\u00e9 Inoc\u00eancio (Marcos Palmeira) para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2365,1117,108,1410,2366,11,197,50],"class_list":["post-1570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-atrapalha","tag-atriz","tag-globo","tag-palavrao","tag-solta","tag-veja","tag-video","tag-vivo"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1570"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1570\/revisions"}],"predecessor-version":[{"id":1572,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1570\/revisions\/1572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1571"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}