{"id":1543,"date":"2024-03-07T12:16:09","date_gmt":"2024-03-07T12:16:09","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/07\/prf-troca-tiros-com-milicianos-em-rodovia-do-rj-veja-video\/"},"modified":"2024-03-07T12:21:04","modified_gmt":"2024-03-07T12:21:04","slug":"prf-troca-tiros-com-milicianos-em-rodovia-do-rj-veja-video","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/07\/prf-troca-tiros-com-milicianos-em-rodovia-do-rj-veja-video\/","title":{"rendered":"PRF troca tiros com milicianos em rodovia do RJ; VEJA V\u00cdDEO"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Agentes da Pol\u00edcia Rodovi\u00e1ria Federal (PRF) entraram em confronto armado com milicianos na BR-101, em Campo Grande, na altura do viaduto Engenheiro Oscar de Brito, no Rio de Janeiro, na manh\u00e3 desta quinta-feira (7).<\/p>\n<p>Segundo a PRF, seis milicianos ficaram feridos e foram encaminhados ao Hospital Santa Cruz.<\/p>\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\">\n<p lang=\"pt\" dir=\"ltr\">PRF troca tiros com milicianos em rodovia do RJ <a href=\"https:\/\/t.co\/XBk2hP8M9M\">pic.twitter.com\/XBk2hP8M9M<\/a><\/p>\n<p>\u2014 Diario do Brasil Not\u00edcias (@diariobrasil_n) <a href=\"https:\/\/twitter.com\/diariobrasil_n\/status\/1765712964592493006?ref_src=twsrc%5Etfw\">March 7, 2024<\/a><\/p><\/blockquote>\n<p>A Pol\u00edcia Civil do Rio de Janeiro confirmou que a Delegacia de Repress\u00e3o \u00e0s A\u00e7\u00f5es Criminosas Organizadas (Draco) atuou no trabalho de investiga\u00e7\u00e3o e monitoramento da ocorr\u00eancia.<\/p>\n<p>Quatro ve\u00edculos foram recuperados e armas foram apreendidas. Nove indiv\u00edduos foram conduzidos \u00e0 Draco, onde a ocorr\u00eancia ser\u00e1 apresentada e seguir\u00e1 com as investiga\u00e7\u00f5es.<\/p>\n<p>A\u00a0<strong>CNN<\/strong>\u00a0confirmou que a troca de tiros entre a PRF e o grupo de 15 milicianos envolveu o \u201cBonde do Zinho\u201d, quadrilha de Lu\u00eds Ant\u00f4nio da Silva Braga.<\/p>\n<p>Braga, mais conhecido como \u2018Zinho\u2019, estava foragido desde 2018, e se entregou \u00e0 PF em 24 de dezembro do ano passado, ap\u00f3s a Opera\u00e7\u00e3o Batismo.<\/p>\n<p><strong><em>Com informa\u00e7\u00f5es de CNN<\/em><\/strong><\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/prf-troca-tiros-com-milicianos-em-rodovia-do-rj-veja-video\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agentes da Pol\u00edcia Rodovi\u00e1ria Federal (PRF) entraram em confronto armado com milicianos na BR-101, em Campo Grande, na altura do viaduto Engenheiro Oscar de Brito, no Rio de Janeiro, na manh\u00e3 desta quinta-feira (7). Segundo a PRF, seis milicianos ficaram feridos e foram encaminhados ao Hospital Santa Cruz. PRF troca tiros com milicianos em rodovia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2331,1337,2332,1733,2330,11,197],"class_list":["post-1543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-milicianos","tag-prf","tag-rodovia","tag-tiros","tag-troca","tag-veja","tag-video"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1543"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1543\/revisions"}],"predecessor-version":[{"id":1545,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1543\/revisions\/1545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1544"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}