{"id":1462,"date":"2024-03-05T23:22:48","date_gmt":"2024-03-05T23:22:48","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/05\/cacique-em-brumadinho-e-militante-da-causa-indigena-e-encontrado-morto\/"},"modified":"2024-03-05T23:26:23","modified_gmt":"2024-03-05T23:26:23","slug":"cacique-em-brumadinho-e-militante-da-causa-indigena-e-encontrado-morto","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/05\/cacique-em-brumadinho-e-militante-da-causa-indigena-e-encontrado-morto\/","title":{"rendered":"Cacique em Brumadinho e militante da causa ind\u00edgena \u00e9 encontrado morto"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Reprodu\u00e7\u00e3o Museu do \u00cdndio<\/p>\n<h2 class=\"wp-block-heading\">Merong Kamak\u00e3 tinha 36 anos e era defensor da preserva\u00e7\u00e3o dos territ\u00f3rios ind\u00edgenas em todo o Brasil; Pol\u00edcia investiga<\/h2>\n<p>O cacique Merong Kamak\u00e3 Mongoi\u00f3, l\u00edder do povo ind\u00edgena Patax\u00f3-h\u00e3-h\u00e3-h\u00e3e, foi encontrado desacordado na \u00faltima segunda-feira (4) na aldeia Kamak\u00e3 Mongoi\u00f3, em Brumadinho, Minas Gerais.<\/p>\n<p>Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, o cacique de 36 anos foi socorrido mas n\u00e3o resistiu. A per\u00edcia esteve no local e o corpo foi levado para o Instituto M\u00e9dico Legal de Betim, onde passou por exame de necropsia. Nesta ter\u00e7a-feira, a fam\u00edlia realizou o vel\u00f3rio e amanh\u00e3 (6) ser\u00e1 o sepultamento.<\/p>\n<p>A Pol\u00edcia Federal de Minas Gerais est\u00e1 \u00e0 frente das investiga\u00e7\u00f5es.<\/p>\n<h2 class=\"wp-block-heading\">Quem foi o Cacique Merong Kamak\u00e3 Mongoi\u00f3<\/h2>\n<p>Nascido no munic\u00edpio de Contagem, no interior do estado mineiro, Merong Kamak\u00e3 foi morar com na Bahia quando crian\u00e7a, segundo a nota de pesar da Funai.<\/p>\n<p>De acordo com o Museu do \u00cdndio, no Rio de Janeiro, a inf\u00e2ncia foi uma \u00e9poca de dificuldades para a fam\u00edlia do cacique, que n\u00e3o contava com apoio dos governos nem com a venda de artesanato para subsist\u00eancia.<\/p>\n<p>J\u00e1 adulto, Merong se tornou militante em defesa dos territ\u00f3rios de seu povo e de outros grupos \u00e9tnicos, como o Kaing\u00e1ng, Xokleng, Guarani e trabalhou na Ocupa\u00e7\u00e3o Lanceiros Negros, que apoiou povos ind\u00edgenas do Rio Grande do Sul a terem suas terras de volta.<\/p>\n<p>Em Brumadinho, onde foi encontrado sem vida, o cacique liderava a retomada do territ\u00f3rio Patax\u00f3-h\u00e3-h\u00e3-h\u00e3e no munic\u00edpio.<\/p>\n<p>Segundo a nota de mem\u00f3ria do Conselho Ind\u00edgena Mission\u00e1rio (Cimi), Merong Kamak\u00e3 Mongoi\u00f3 deixa dois filhos. A nota relembra o pensamento do l\u00edder ind\u00edgena em sua \u00faltima a\u00e7\u00e3o na cidade mineira.<\/p>\n<p>\u201cN\u00f3s, povos ind\u00edgenas, fomos guiados at\u00e9 aqui pelo Grande Esp\u00edrito para ocupar e cuidar dessas terras. E tamb\u00e9m para alertar a sociedade que alguns ainda est\u00e3o dormindo e n\u00e3o viram o grande estrago que a minera\u00e7\u00e3o est\u00e1 causando\u201d, dizia Merong.<\/p>\n<p>Ele costumava relatar a press\u00e3o psicol\u00f3gica de grandes empresas, latifundi\u00e1rios e at\u00e9 mesmo das autoridades contra os povos ind\u00edgenas para desocupar territ\u00f3rios, e lutou contra isso at\u00e9 sua morte.<\/p>\n<p>CNN<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/cacique-em-brumadinho-e-militante-da-causa-indigena-e-encontrado-morto\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reprodu\u00e7\u00e3o Museu do \u00cdndio Merong Kamak\u00e3 tinha 36 anos e era defensor da preserva\u00e7\u00e3o dos territ\u00f3rios ind\u00edgenas em todo o Brasil; Pol\u00edcia investiga O cacique Merong Kamak\u00e3 Mongoi\u00f3, l\u00edder do povo ind\u00edgena Patax\u00f3-h\u00e3-h\u00e3-h\u00e3e, foi encontrado desacordado na \u00faltima segunda-feira (4) na aldeia Kamak\u00e3 Mongoi\u00f3, em Brumadinho, Minas Gerais. Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, o cacique [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2238,2237,223,1818,2240,2239,195],"class_list":["post-1462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-brumadinho","tag-cacique","tag-causa","tag-encontrado","tag-indigena","tag-militante","tag-morto"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1462"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1462\/revisions"}],"predecessor-version":[{"id":1464,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1462\/revisions\/1464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1463"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}