{"id":1408,"date":"2024-03-04T18:23:55","date_gmt":"2024-03-04T18:23:55","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/04\/diplomata-brasileiro-morre-durante-missao-em-ruanda-na-africa\/"},"modified":"2024-03-04T18:24:09","modified_gmt":"2024-03-04T18:24:09","slug":"diplomata-brasileiro-morre-durante-missao-em-ruanda-na-africa","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/04\/diplomata-brasileiro-morre-durante-missao-em-ruanda-na-africa\/","title":{"rendered":"Diplomata brasileiro morre durante miss\u00e3o em Ruanda, na \u00c1frica"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Neste domingo (3\/3), o diplomata brasileiro Daniel Machado da Fonseca faleceu durante uma miss\u00e3o em Kigali, Ruanda, onde estava participando de uma reuni\u00e3o do Conselho do Fundo Verde para o Clima. A morte resultou na suspens\u00e3o das atividades programadas devido a esse tr\u00e1gico acontecimento.<\/p>\n<p>\u201cPermitindo um dia de luto, as atividades do Conselho ser\u00e3o canceladas no dia 4 de mar\u00e7o. A reuni\u00e3o oficial do Conselho do GCF [Fundo Verde] ser\u00e1 realizada no dia 5 de mar\u00e7o, quando haver\u00e1 uma cerim\u00f4nia para homenagear a vida de Daniel, seu legado como defensor de comunidades vulner\u00e1veis ao clima e na promo\u00e7\u00e3o da a\u00e7\u00e3o clim\u00e1tica global\u201d, diz nota do grupo.<\/p>\n<p>As informa\u00e7\u00f5es dispon\u00edveis indicam que ele sofreu uma parada card\u00edaca.<\/p>\n<p>Daniel, amplamente apreciado por colegas de profiss\u00e3o, familiares e amigos, origin\u00e1rio do Rio de Janeiro, ingressou no Itamaraty em 2006, acumulando experi\u00eancia nas embaixadas brasileiras em Nair\u00f3bi, Roma e Nova D\u00e9li.<\/p>\n<p>No momento, ocupava o cargo de chefe da Divis\u00e3o de A\u00e7\u00e3o Clim\u00e1tica do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores.<\/p>\n<h4 class=\"wp-block-heading\">Governo e amigos elogiam diplomata<\/h4>\n<p>\u201cSua trajet\u00f3ria no Itamaraty foi marcada por reconhecidas compet\u00eancia e dedica\u00e7\u00e3o. Contou sempre com o respeito e o carinho de todos seus colegas, no Brasil e no exterior\u201d, diz nota assinada pelo ministro Mauro Vieira e pela secret\u00e1ria-geral das Rela\u00e7\u00f5es Exteriores, Maria Laura da Rocha.<\/p>\n<p>Amigos tamb\u00e9m lamentaram a morte dele. \u201cFoi um excelente ser humano. Os que o conhecem lamentam todos os anos de conv\u00edvio pessoal e profissional que perdemos por conta desta partida t\u00e3o prematura\u201d, comentou a diplomata Clarissa Forecchi, amiga de Daniel.<\/p>\n<p>Ele era casado com a tamb\u00e9m diplomata Roberta Maria Lima Ferreira. O casal tinha uma filha.<\/p>\n<p><em>Com informa\u00e7\u00f5es de Metr\u00f3poles<\/em><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/diplomata-brasileiro-morre-durante-missao-em-ruanda-na-africa\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo (3\/3), o diplomata brasileiro Daniel Machado da Fonseca faleceu durante uma miss\u00e3o em Kigali, Ruanda, onde estava participando de uma reuni\u00e3o do Conselho do Fundo Verde para o Clima. A morte resultou na suspens\u00e3o das atividades programadas devido a esse tr\u00e1gico acontecimento. \u201cPermitindo um dia de luto, as atividades do Conselho ser\u00e3o canceladas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2175,254,2172,307,2173,420,2174],"class_list":["post-1408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-africa","tag-brasileiro","tag-diplomata","tag-durante","tag-missao","tag-morre","tag-ruanda"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1408"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1408\/revisions"}],"predecessor-version":[{"id":1410,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1408\/revisions\/1410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1409"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}