{"id":1393,"date":"2024-03-04T12:11:01","date_gmt":"2024-03-04T12:11:01","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/04\/buscas-da-pf-receita-de-bolo-com-neston-o-arquivo-que-intriga-investigadores\/"},"modified":"2024-03-04T12:35:55","modified_gmt":"2024-03-04T12:35:55","slug":"buscas-da-pf-receita-de-bolo-com-neston-o-arquivo-que-intriga-investigadores","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/04\/buscas-da-pf-receita-de-bolo-com-neston-o-arquivo-que-intriga-investigadores\/","title":{"rendered":"Buscas da PF : Receita de bolo com Neston: o arquivo que intriga investigadores"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><em>Beto Barata\/PL\/<\/em><\/p>\n<p>Um Rolex prateado e um rel\u00f3gio de luxo su\u00ed\u00e7o da marca Audemars Piguet dividiam com uma pepita de ouro, uma arma com registro vencido e 31.100 reais em dinheiro vivo espa\u00e7o no cofre do apartamento do presidente nacional do Partido Liberal (PL)\u00a0<strong>Valdemar Costa Neto<\/strong>.<\/p>\n<p>As descobertas foram feitas pela Pol\u00edcia Federal durante a ordem de busca determinada pelo ministro do Supremo Tribunal Federal (STF) Alexandre de Moraes na investiga\u00e7\u00e3o que mira autoridades suspeitas de tramar um golpe de Estado para garantir a perman\u00eancia de Jair\u00a0Bolsonaro\u00a0no poder. Costa Neto acabaria preso \u2013 e liberado tr\u00eas dias depois \u2013 por causa da arma, cujo registro federal, em nome do filho, havia expirado desde 2018.<\/p>\n<p>Alvo de busca e apreens\u00e3o de documentos, celulares e computadores, uma importante fonte de coleta de provas para que a PF avalie a eventual participa\u00e7\u00e3o de cada suspeito na trama golpista \u2013 ao PL, por exemplo, coube questionar a seguran\u00e7a das urnas eletr\u00f4nicas, o que levou o ministro Alexandre a impor uma multa de cerca de 23 milh\u00f5es de reais \u00e0 legenda \u2013 Valdemar tamb\u00e9m teve apreendidos 27 cartuchos .38 que estavam guardados em uma estante, cinco outros relacionados ao rev\u00f3lver Smith&#038;Wesson recolhido, al\u00e9m de pouco mais de 22.600 reais espalhados pelo im\u00f3vel e um terceiro rel\u00f3gio, um Bulgari dourado.<\/p>\n<h3 class=\"wp-block-heading\">Receita de bolo com Neston: o arquivo que intriga investigadores<\/h3>\n<p>Tamb\u00e9m alvo de buscas, o tenente-coronel Guilherme Marques Almeida, do comando do 1\u00ba Batalh\u00e3o de Opera\u00e7\u00f5es Psicol\u00f3gicas do Ex\u00e9rcito, tornou-se c\u00e9lebre na Opera\u00e7\u00e3o Tempus Veritatis por ter passado mal ao ser informado pela\u00a0Pol\u00edcia Federal\u00a0da ordem expedida pelo ministro do Supremo, mas um arquivo em espec\u00edfico encontrado em seus pertences intrigou os investigadores.<\/p>\n<p>A partir da an\u00e1lise do conte\u00fado de um HD externo, a PF registrou um coment\u00e1rio \u00e0 parte nos autos de apreens\u00e3o: um arquivo salvo com o nome de uma receita de bolo na verdade pode ter pouca rela\u00e7\u00e3o com a suposta prefer\u00eancia culin\u00e1ria do alvo.<\/p>\n<p>Isso porque, ao tentarem abrir a lista de ingredientes e o modo de preparo da sobremesa, os investigadores se depararam com um arquivo protegido por senha. Diz a PF: \u201cChama a aten\u00e7\u00e3o arquivo do tipo .docx denominado \u2018Receita de Bolo com Neston\u2019, visto que o referido documento possui denomina\u00e7\u00e3o de conte\u00fado simples, todavia possui senha para abrir o arquivo\u201d.<\/p>\n<p>Exonerado no \u00faltimo dia 21 na esteira da opera\u00e7\u00e3o policial, Guilherme tinha 13.702 imagens armazenadas no celular pessoal e mais de 5.300 v\u00eddeos, entre os quais loas \u00e0s For\u00e7as Armadas, teorias conspirat\u00f3rias sobre urnas eletr\u00f4nicas e not\u00edcias de que Mauro Cid, ex-ajudante de ordens do ex-presidente Jair Bolsonaro, havia fechado um acordo de dela\u00e7\u00e3o premiada.<\/p>\n<h3 class=\"wp-block-heading\">Arsenal com oficial do Ex\u00e9rcito<\/h3>\n<p>No im\u00f3vel relacionado ao tenente-coronel Ronald Ferreira de Ara\u00fajo J\u00fanior, apontado como interlocutor de Mauro Cid para monitorar a\u00e7\u00f5es contra Bolsonaro tomadas pelo Judici\u00e1rio e medir a temperatura de manifestantes acampados em frente do QG do Ex\u00e9rcito, em Bras\u00edlia, foram encontradas mais de 500 muni\u00e7\u00f5es de diferentes calibres, quatro pistolas Taurus e um rev\u00f3lver do mesmo fabricante, um rev\u00f3lver Rossi, uma pistola Sig Sauer 9mm, uma pistola Beretta calibre .22, um rev\u00f3lver S&#038;W calibre .22 e uma carabina Taurus 9mm. Todas as armas tinham registro.<\/p>\n<p>Veja<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/buscas-da-pf-receita-de-bolo-com-neston-o-arquivo-que-intriga-investigadores\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beto Barata\/PL\/ Um Rolex prateado e um rel\u00f3gio de luxo su\u00ed\u00e7o da marca Audemars Piguet dividiam com uma pepita de ouro, uma arma com registro vencido e 31.100 reais em dinheiro vivo espa\u00e7o no cofre do apartamento do presidente nacional do Partido Liberal (PL)\u00a0Valdemar Costa Neto. As descobertas foram feitas pela Pol\u00edcia Federal durante a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2154,2008,774,2155,2156,2153,2152],"class_list":["post-1393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-arquivo","tag-bolo","tag-buscas","tag-intriga","tag-investigadores","tag-neston","tag-receita"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1393"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1393\/revisions"}],"predecessor-version":[{"id":1395,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1393\/revisions\/1395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1394"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}