{"id":1325,"date":"2024-03-02T22:52:43","date_gmt":"2024-03-02T22:52:43","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/02\/torcedor-morre-em-confronto-entre-torcidas-de-cruzeiro-e-atletico-mg\/"},"modified":"2024-03-03T03:37:49","modified_gmt":"2024-03-03T03:37:49","slug":"torcedor-morre-em-confronto-entre-torcidas-de-cruzeiro-e-atletico-mg","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/03\/02\/torcedor-morre-em-confronto-entre-torcidas-de-cruzeiro-e-atletico-mg\/","title":{"rendered":"Torcedor morre em confronto entre torcidas de Cruzeiro e Atl\u00e9tico-MG"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Neste s\u00e1bado (2\/3), um tr\u00e1gico epis\u00f3dio marcou o futebol em Belo Horizonte, quando uma briga entre torcidas organizadas de Cruzeiro e Atl\u00e9tico-MG resultou na morte de um torcedor e deixou outros dois feridos por disparos de arma de fogo, no bairro do Barreiro.<\/p>\n<p>Os eventos ocorreram simultaneamente aos jogos do Campeonato Mineiro, nos quais o Cruzeiro enfrentou o Uberl\u00e2ndia no Mineir\u00e3o e o Atl\u00e9tico-MG recebeu o Ipatinga na Arena MRV. O torcedor do Cruzeiro, hospitalizado ap\u00f3s a briga, n\u00e3o resistiu aos ferimentos.<\/p>\n<p>A Pol\u00edcia Militar agiu prontamente e deteve duas pessoas, al\u00e9m de apreender uma arma de fogo e um ve\u00edculo relacionados ao incidente. A viol\u00eancia entre torcidas, lamentavelmente, resultou em mais uma perda no cen\u00e1rio esportivo, refor\u00e7ando a necessidade de medidas eficazes para conter confrontos e garantir a seguran\u00e7a nos eventos esportivos.<\/p>\n<p>O fato destaca a import\u00e2ncia de a\u00e7\u00f5es preventivas e colaborativas entre clubes, autoridades e torcedores para assegurar um ambiente pac\u00edfico e seguro nos entornos e est\u00e1dios durante as partidas. A sociedade esportiva se une em luto pela perda e espera que epis\u00f3dios como esse sirvam como alerta para a implementa\u00e7\u00e3o de medidas que evitem futuros incidentes.<\/p>\n<p>Com informa\u00e7\u00f5es do Metr\u00f3poles.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/03\/torcedor-morre-em-confronto-entre-torcidas-de-cruzeiro-e-atletico-mg\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste s\u00e1bado (2\/3), um tr\u00e1gico epis\u00f3dio marcou o futebol em Belo Horizonte, quando uma briga entre torcidas organizadas de Cruzeiro e Atl\u00e9tico-MG resultou na morte de um torcedor e deixou outros dois feridos por disparos de arma de fogo, no bairro do Barreiro. Os eventos ocorreram simultaneamente aos jogos do Campeonato Mineiro, nos quais o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2079,934,341,970,420,2077,2078],"class_list":["post-1325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-atleticomg","tag-confronto","tag-cruzeiro","tag-entre","tag-morre","tag-torcedor","tag-torcidas"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1325"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1325\/revisions"}],"predecessor-version":[{"id":1327,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1325\/revisions\/1327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1326"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}