{"id":1118,"date":"2024-02-27T22:59:52","date_gmt":"2024-02-27T22:59:52","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/27\/metro-diz-que-nao-registrou-incidentes-com-bolsonaristas-gavioes-se-cala\/"},"modified":"2024-02-28T07:02:27","modified_gmt":"2024-02-28T07:02:27","slug":"metro-diz-que-nao-registrou-incidentes-com-bolsonaristas-gavioes-se-cala","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/27\/metro-diz-que-nao-registrou-incidentes-com-bolsonaristas-gavioes-se-cala\/","title":{"rendered":"Metr\u00f4 diz que n\u00e3o registrou \u2018incidentes\u2019 com bolsonaristas; Gavi\u00f5es se cala"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>O Metr\u00f4 de S\u00e3o Paulo enviou uma nota ao\u00a0<strong>UOL\u00a0<\/strong>sobre o epis\u00f3dio de domingo\u00a0envolvendo bolsonaristas e membros da Gavi\u00f5es da Fiel, maior torcida organizada do\u00a0Corinthians.<\/p>\n<h2 class=\"wp-block-heading\">O que aconteceu<\/h2>\n<p><strong>O Metr\u00f4 afirmou que \u201cn\u00e3o registrou incidentes\u201d a respeito<\/strong>. V\u00eddeos que viralizaram nas redes sociais mostram organizados barrando a entrada de manifestantes pr\u00f3-Bolsonaro em um vag\u00e3o.<\/p>\n<p><strong>A companhia destacou \u201ctodos puderam ir e voltar com seguran\u00e7a\u201d no \u00faltimo final de semana<\/strong>. O comunicado cita que a opera\u00e7\u00e3o foi \u201cbem-sucedida\u201d.<\/p>\n<p><strong>Por fim, o Metr\u00f4 ainda repudiou qualquer tipo de discrimina\u00e7\u00e3o<\/strong>, seja por afinidade pol\u00edtica ou religiosa, ra\u00e7a, cor ou g\u00eanero.<\/p>\n<p><strong>A torcida organizada, por sua vez, adotou sil\u00eancio<\/strong>. A assessoria dos organizados afirmou que n\u00e3o ir\u00e1 se pronunciar sobre o ocorrido.<\/p>\n<p><strong>O UOL apurou que, internamente, a Gavi\u00f5es v\u00ea o epis\u00f3dio como uma atitude isolada de alguns membros<\/strong>. \u201c\u00c9 atitude isolada, a Gavi\u00f5es \u00e9 apartid\u00e1ria. N\u00f3s nascemos para apoiar, fiscalizar e cobrar o Corinthians. Quem quiser defender partido pol\u00edtico tem que se afiliar a um\u201d, disse um dirigente da organizada.<\/p>\n<h2 class=\"wp-block-heading\">O que o Metr\u00f4 disse<\/h2>\n<p><em>\u201cO Metr\u00f4 n\u00e3o registrou incidentes a esse respeito. A opera\u00e7\u00e3o no fim de semana foi bem-sucedida e todos puderam ir e voltar com seguran\u00e7a. Refor\u00e7amos que o Metr\u00f4 repudia todo e qualquer discrimina\u00e7\u00e3o seja por ra\u00e7a, cor, g\u00eanero, afinidade pol\u00edtica e ou religiosa.\u201d<\/em>Continua ap\u00f3s a publicidade<\/p>\n<h2 class=\"wp-block-heading\">Barrados no Metr\u00f4<\/h2>\n<p><strong>Alguns membros da organizada estavam uniformizados em um dos vag\u00f5es da linha verde rumo \u00e0 Neo Qu\u00edmica Arena<\/strong>\u00a0\u2014\u00a0o alvinegro jogou contra a Ponte Preta poucas horas depois, em Itaquera, pelo Campeonato Paulista.<\/p>\n<p><strong>Assim que o trem chegou \u00e0 esta\u00e7\u00e3o Para\u00edso e as portas se abriram, manifestantes favor\u00e1veis a\u00a0Jair Bolsonaro\u00a0tentaram entrar<\/strong>. Vestidos de verde e amarelo, eles participaram de um ato na avenida Paulista em defesa do ex-presidente.<\/p>\n<p><strong>\u201cA\u00ed, ningu\u00e9m entra. N\u00e3o v\u00e3o entrar, n\u00e3o. Pode voltar\u201d, bradaram integrantes da torcida<\/strong>. Eles se posicionaram na porta e fizeram uma esp\u00e9cie de barreira, fechando a passagem<\/p>\n<p><strong>Uma das manifestantes se irritou, questionou o motivo da atitude e n\u00e3o teve resposta<\/strong>. Os membros da Gavi\u00f5es, ent\u00e3o, passaram a bradar m\u00fasicas relativas ao time: \u201cTim\u00e3o, e\u00f4\u201d, gritaram eles.Continua ap\u00f3s a publicidade<\/p>\n<p><strong>N\u00e3o houve qualquer tipo de confus\u00e3o<\/strong>, e o metr\u00f4 seguiu normalmente o trajeto rumo \u00e0 esta\u00e7\u00e3o Ana Rosa. H\u00e1 tamb\u00e9m outros v\u00eddeos que circulam nas redes sociais mostrando corintianos contr\u00e1rios a bolsonaristas em outras esta\u00e7\u00f5es do sistema metrovi\u00e1rio p\u00fablico paulistano.<\/p>\n<p>UOL<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/metro-diz-que-nao-registrou-incidentes-com-bolsonaristas-gavioes-se-cala\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Metr\u00f4 de S\u00e3o Paulo enviou uma nota ao\u00a0UOL\u00a0sobre o epis\u00f3dio de domingo\u00a0envolvendo bolsonaristas e membros da Gavi\u00f5es da Fiel, maior torcida organizada do\u00a0Corinthians. O que aconteceu O Metr\u00f4 afirmou que \u201cn\u00e3o registrou incidentes\u201d a respeito. V\u00eddeos que viralizaram nas redes sociais mostram organizados barrando a entrada de manifestantes pr\u00f3-Bolsonaro em um vag\u00e3o. A companhia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1790,1791,243,132,1789,1787,165,1788],"class_list":["post-1118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-bolsonaristas","tag-cala","tag-diz","tag-gavioes","tag-incidentes","tag-metro","tag-nao","tag-registrou"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1118"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1118\/revisions"}],"predecessor-version":[{"id":1120,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1118\/revisions\/1120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1119"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}