{"id":1026,"date":"2024-02-26T16:16:22","date_gmt":"2024-02-26T16:16:22","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/26\/traficante-de-20-anos-conhecida-como-barbie-do-po-e-presa-em-sp\/"},"modified":"2024-02-26T16:20:49","modified_gmt":"2024-02-26T16:20:49","slug":"traficante-de-20-anos-conhecida-como-barbie-do-po-e-presa-em-sp","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/26\/traficante-de-20-anos-conhecida-como-barbie-do-po-e-presa-em-sp\/","title":{"rendered":"Traficante de 20 anos conhecida como \u2018Barbie do P\u00f3\u2019 \u00e9 presa em SP"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>A Pol\u00edcia Militar de S\u00e3o Paulo efetuou a pris\u00e3o em flagrante de Eduarda Marques, uma jovem de 20 anos, na \u00faltima quarta-feira. A deten\u00e7\u00e3o ocorreu ap\u00f3s os agentes observarem uma \u2018atitude suspeita\u2019 enquanto ela guardava drogas em uma \u00e1rea rural de S\u00e3o Jos\u00e9 do Rio Preto.<\/p>\n<p>Durante a investiga\u00e7\u00e3o, os policiais encontraram 13 pinos de coca\u00edna e uma por\u00e7\u00e3o de maconha em um apartamento, juntamente com a quantia de R$ 340. O incidente foi registrado como porte ilegal de drogas. Al\u00e9m disso, um adolescente de 16 anos tamb\u00e9m foi apreendido durante a opera\u00e7\u00e3o.<\/p>\n<figure class=\"wp-block-image size-full\"><picture decoding=\"async\" class=\"wp-image-107905\"><source type=\"image\/webp\" srcset=\"https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/02\/image-260.png.webp 462w, https:\/\/terrabrasilnoticias.com\/wp-content\/uploads\/2024\/02\/image-260-240x300.png.webp 240w\" sizes=\"(max-width: 462px) 100vw, 462px\"\/><\/picture>\n<\/figure>\n<p class=\"has-small-font-size\"><em>\u2018Barbie do P\u00f3\u2019: traficante de 20 anos \u00e9 presa com pinos de coca\u00edna e maconha em SP \u2014 Foto: Reprodu\u00e7\u00e3o<\/em><\/p>\n<p>Nas plataformas digitais, a figura conhecida como \u2018Barbie do P\u00f3\u2019 era previamente reconhecida como blogueira e influenciadora. Com uma base de mais de 20 mil seguidores, Eduarda compartilhava regularmente momentos como modelo, festas e proezas arriscadas em motocicletas.<\/p>\n<p>O GLOBO procurou entrar em contato com a defesa de Eduarda Marques, por\u00e9m, at\u00e9 a divulga\u00e7\u00e3o desta mat\u00e9ria, n\u00e3o obteve sucesso.<\/p>\n<p><strong><em>Com informa\u00e7\u00f5es de O Globo<\/em><\/strong><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/traficante-de-20-anos-conhecida-como-barbie-do-po-e-presa-em-sp\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Militar de S\u00e3o Paulo efetuou a pris\u00e3o em flagrante de Eduarda Marques, uma jovem de 20 anos, na \u00faltima quarta-feira. A deten\u00e7\u00e3o ocorreu ap\u00f3s os agentes observarem uma \u2018atitude suspeita\u2019 enquanto ela guardava drogas em uma \u00e1rea rural de S\u00e3o Jos\u00e9 do Rio Preto. Durante a investiga\u00e7\u00e3o, os policiais encontraram 13 pinos de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[231,1672,61,1671,1673,412,860],"class_list":["post-1026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-anos","tag-barbie","tag-como","tag-conhecida","tag-po","tag-presa","tag-traficante"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1026"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1026\/revisions"}],"predecessor-version":[{"id":1028,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1026\/revisions\/1028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1027"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}