{"id":1017,"date":"2024-02-26T11:13:30","date_gmt":"2024-02-26T11:13:30","guid":{"rendered":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/26\/ultimo-minuto-primeiro-ministro-palestino-renuncia-ao-cargo\/"},"modified":"2024-02-26T11:16:10","modified_gmt":"2024-02-26T11:16:10","slug":"ultimo-minuto-primeiro-ministro-palestino-renuncia-ao-cargo","status":"publish","type":"post","link":"https:\/\/tvfloridausa.com\/inscreva-se\/2024\/02\/26\/ultimo-minuto-primeiro-ministro-palestino-renuncia-ao-cargo\/","title":{"rendered":"\u00daltimo Minuto: primeiro-ministro palestino renuncia ao cargo"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Nesta segunda-feira (26), Mohammad Shtayyeh, primeiro-ministro palestino e membro da Autoridade Nacional Palestina (ANP), renunciou ao cargo. A ANP, estabelecida h\u00e1 tr\u00eas d\u00e9cadas, exerce uma governan\u00e7a restrita sobre \u00e1reas da Cisjord\u00e2nia ocupada.<\/p>\n<p>\u201cApresentei a demiss\u00e3o ao l\u00edder [da ANP, Mahmud Abbas] em 20 de fevereiro e a submeto hoje por escrito\u201d, afirmou Shtayyeh, antes de explicar que a decis\u00e3o acontece \u201c\u00e0 luz dos fatos relacionados com a agress\u00e3o contra a Faixa de Gaza e a escalada na Cisjord\u00e2nia e Jerusal\u00e9m\u201d.<\/p>\n<p>Shtayyeh anunciou sua ren\u00fancia, afirmando que Gaza precisa passar por uma nova fase de governo devido \u00e0 atual realidade na regi\u00e3o. O primeiro-ministro palestino assumiu o cargo em 2019.<\/p>\n<p>Desde o in\u00edcio da guerra em Gaza, em 7 de outubro de 2023, o l\u00edder da Autoridade Nacional Palestina (ANP) tem enfrentado cr\u00edticas por sua suposta \u201cimpot\u00eancia\u201d diante dos bombardeios israelenses na Faixa de Gaza e do aumento da viol\u00eancia na Cisjord\u00e2nia ocupada.<\/p>\n<p>Por cerca de 17 anos, a lideran\u00e7a palestina tem sido dividida entre a Autoridade Nacional Palestina (ANP) e o Hamas, que governa a Faixa de Gaza.<\/p>\n<p>\u201c[O novo momento] exigir\u00e1 acordos governamentais e pol\u00edticos que levem em conta a realidade emergente na Faixa de Gaza, bem como a necessidade urgente de um consenso palestino\u201d, afirmou Shtayyeh. Al\u00e9m disso, \u201c\u00e9 necess\u00e1ria a extens\u00e3o da Autoridade Nacional Palestina sobre todo o territ\u00f3rio\u201d.<\/p>\n<p>Por\u00e9m, a ren\u00fancia de Shtayyeh ainda dever\u00e1 ser aceita pelo l\u00edder da ANP, que poder\u00e1 pedir que ele permane\u00e7a como interino at\u00e9 que um substituto seja nomeado.<\/p>\n<h2 class=\"wp-block-heading\">Autoridade Nacional Palestina (ANP)<\/h2>\n<p>Israel assegurou seu compromisso de eliminar o Hamas e afirmou que, por motivos de seguran\u00e7a, n\u00e3o permitir\u00e1 a Autoridade Nacional Palestina (ANP) dominar Gaza ap\u00f3s o conflito, que resultou na morte de aproximadamente 1.200 israelenses e quase 30 mil palestinos.<\/p>\n<p>Originalmente, a ANP estava destinada a ser um \u00f3rg\u00e3o tempor\u00e1rio de governo para todos os territ\u00f3rios palestinos, composto por um l\u00edder, primeiro-ministro e conselho legislativo. O Fatah, o maior partido pol\u00edtico palestino, e o grupo terrorista Hamas teriam a oportunidade de concorrer a cadeiras nesse \u00f3rg\u00e3o.<\/p>\n<p>Entretanto, um conflito surgiu entre os dois partidos ap\u00f3s a \u00faltima elei\u00e7\u00e3o para o Conselho Nacional Palestino, em 2006. Naquela \u00e9poca, o grupo terrorista conquistou as cadeiras do conselho, mas essa vit\u00f3ria n\u00e3o foi reconhecida por Israel e pela Uni\u00e3o Europeia, que contribu\u00edam financeiramente para a ANP.<\/p>\n<p>Essa discord\u00e2ncia resultou em san\u00e7\u00f5es por parte desses pa\u00edses, intensificando a rivalidade entre os partidos locais. O Fatah, como resposta, dissolveu o conselho, mantendo o controle da ANP na Cisjord\u00e2nia, onde possu\u00eda sua principal base de apoio. Enquanto isso, o Hamas estabeleceu seu pr\u00f3prio governo e assumiu o controle da Faixa de Gaza.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Esfor\u00e7os para um novo governo<\/strong><\/h2>\n<p>O partido liderado por Shtayyeh, o Fatah, e o Hamas est\u00e3o empenhados em alcan\u00e7ar um acordo para formar um governo de unidade. As duas fac\u00e7\u00f5es devem se reunir na quarta-feira (28) para discutir essa quest\u00e3o.<\/p>\n<p>\u201cA ren\u00fancia de Shtayyeh s\u00f3 faz sentido se ocorrer um acordo de consenso nacional sobre os preparativos para a pr\u00f3xima fase [de Gaza]\u201d, disse Sami Abu Zuhri, o integrante da alta c\u00fapula do Hamas, \u00e0 Reuters.<\/p>\n<p><strong><em>Com informa\u00e7\u00f5es de G1<\/em><\/strong><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/terrabrasilnoticias.com\/2024\/02\/ultimo-minuto-primeiro-ministro-palestino-renuncia-ao-cargo\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta segunda-feira (26), Mohammad Shtayyeh, primeiro-ministro palestino e membro da Autoridade Nacional Palestina (ANP), renunciou ao cargo. A ANP, estabelecida h\u00e1 tr\u00eas d\u00e9cadas, exerce uma governan\u00e7a restrita sobre \u00e1reas da Cisjord\u00e2nia ocupada. \u201cApresentei a demiss\u00e3o ao l\u00edder [da ANP, Mahmud Abbas] em 20 de fevereiro e a submeto hoje por escrito\u201d, afirmou Shtayyeh, antes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1018,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1663,803,1661,1660,1662,1268],"class_list":["post-1017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-cargo","tag-minuto","tag-palestino","tag-primeiroministro","tag-renuncia","tag-ultimo"],"_links":{"self":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/comments?post=1017"}],"version-history":[{"count":1,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1017\/revisions"}],"predecessor-version":[{"id":1019,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/posts\/1017\/revisions\/1019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media\/1018"}],"wp:attachment":[{"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/media?parent=1017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/categories?post=1017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvfloridausa.com\/inscreva-se\/wp-json\/wp\/v2\/tags?post=1017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}